{"id":1529,"date":"2024-10-04T15:55:59","date_gmt":"2024-10-04T15:55:59","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=1529"},"modified":"2026-01-06T16:05:14","modified_gmt":"2026-01-06T16:05:14","slug":"la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/","title":{"rendered":"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1529?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><h3 style=\"text-align: center;\">\u00ab\u00a0Car o\u00f9 est ton tr\u00e9sor, l\u00e0 aussi sera ton c\u0153ur\u2026\u00a0\u00bb<strong>\u00a0 <\/strong><\/h3>\n<h3 style=\"text-align: center;\">Matthieu 6,21<\/h3>\n<p>&nbsp;<\/p>\n<p>A l\u2019approche du 7 octobre, F\u00eate de Notre Dame du Rosaire, il est urgent d\u2019imiter le n\u00e9gociant de l\u2019Evangile\u00a0: \u00ab\u00a0Quand il a trouv\u00e9 une perle de grande valeur, il va vendre tout ce qu\u2019il poss\u00e8de et ach\u00e8te cette perle\u00a0!\u00a0\u00bb (Mt 13,45). Mais avons-nous d\u00e9couvert que le Rosaire est cette \u00ab\u00a0perle unique\u00a0\u00bb de la vie chr\u00e9tienne et ce \u00ab\u00a0tr\u00e9sor sans fond\u00a0\u00bb de l\u2019Evangile, cach\u00e9 en notre c\u0153ur\u00a0? Il faut se souvenir ici de la premi\u00e8re Apparition de Notre Dame \u00e0 Fatima \u00e0 travers le regard de la petite Jacinta\u00a0:<\/p>\n<p>\u00ab\u00a0La Dame avait les mains jointes, comme ceci &#8211; et Jacinta se levait et joignait les mains pour imiter la vision \u2013\u00a0Entre les doigts, elle avait un chapelet. Ah\u00a0! quel beau chapelet elle avait\u00a0!&#8230; tout en or, brillant comme les \u00e9toiles de la nuit, et un Crucifix qui brillait, qui brillait\u2026 Ah\u00a0! quelle belle Dame<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>\u00a0!\u00a0\u00bb<\/p>\n<p>Cependant, toute splendide qu\u2019elle soit, cette premi\u00e8re Apparition n\u2019est pas sans surprise\u00a0!<\/p>\n<p>Lucie manifeste \u00e0 la Vierge son \u00e9tonnement que Francisco ne voit, ni n\u2019entende rien\u00a0? La Dame se tourna alors vers le petit gar\u00e7on et le regarda avec une expression m\u00eal\u00e9e de bont\u00e9 et de maternel reproche\u00a0:<\/p>\n<ul>\n<li>\u00ab\u00a0Oui, il ira\u00a0; mais il devra dire beaucoup de chapelets\u00a0!\u00a0\u00bb<\/li>\n<\/ul>\n<p>En effet, il faut savoir que Francisco ne priait pas assez le chapelet et l\u2019avait d\u00e9lib\u00e9r\u00e9ment \u00ab\u00a0raccourci<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>\u00a0\u00bb\u00a0! Alors, quand Lucia se plaint \u00e0 la Vierge que Francisco ne la voit pas, la r\u00e9ponse de la Dame est pr\u00e9cise\u00a0:<\/p>\n<ul>\n<li>\u00ab\u00a0Dis-lui de r\u00e9citer le chapelet et il me verra aussi\u00a0!\u00a0\u00bb<\/li>\n<\/ul>\n<p>Lucia fait la commission et Francisco commence \u00e0 r\u00e9citer le chapelet\u2026 Apr\u00e8s quelques Ave Maria, il voit tout \u00e0 coup la Dame dont l\u2019\u00e9clat l\u2019\u00e9blouit\u00a0! Par contre, il ne l\u2019entend pas et il restera silencieux et m\u00e9ditatif. Ce n\u2019est qu\u2019apr\u00e8s le d\u00e9part de la Vierge qu\u2019il se fera r\u00e9p\u00e9ter ses paroles par Jacinta et Lucia. Et quand cette derni\u00e8re lui dit que Notre Dame l\u2019emm\u00e8nerait au Ciel, mais qu\u2019il devrait prier beaucoup de chapelets, il s\u2019exclama\u00a0:<\/p>\n<ul>\n<li>\u00ab\u00a0O, ma Notre-Dame, des chapelets, j\u2019en r\u00e9citerai autant que vous le voudrez\u00a0!\u00a0\u00bb<\/li>\n<\/ul>\n<p>C\u2019est une promesse \u00e0 laquelle il restera tr\u00e8s fid\u00e8le car, dans sa si belle \u00e2me, on le verra au quotidien dire seul de nombreux chapelets\u00a0! Nous ressemblons tous \u00e0 Francisco et face \u00e0 nos fragilit\u00e9s, nous avons \u00e0 rebondir comme lui dans un esprit de conversion \u00e9vang\u00e9lique en nous confiant fort \u00e0 la Vierge\u2026<\/p>\n<p>Nous n\u2019avons pas encore saisi le myst\u00e8re de puissance du Rosaire, cette pri\u00e8re qui peut changer nos vies et transformer le monde\u00a0! Car il y a un secret dans la r\u00e9citation de cette pri\u00e8re mariale qui nous emporte dans l\u2019immense vague de l\u2019Esprit \u00ab\u00a0cach\u00e9e\u00a0\u00bb dans la simplicit\u00e9 de la r\u00e9p\u00e9titivit\u00e9\u2026 une sorte de corde sacr\u00e9e vers l\u2019au-del\u00e0 \u00e0 laquelle on s\u2019accroche et nous ouvre d\u00e9j\u00e0 les portes du Ciel\u00a0!<\/p>\n<p>Le monde des Saints et Saintes l\u2019a transpir\u00e9 merveilleusement et il n\u2019est qu\u2019\u00e0 les \u00e9couter pour le d\u00e9couvrir\u2026 car en priant le Rosaire, on d\u00e9couvre comme eux que \u00ab\u00a0Marie est comme un beau fleuve qui, sans r\u00e9serve et dans la pl\u00e9nitude de son flot, s\u2019\u00e9coule vers Dieu. Tout ce qui s\u2019abandonne \u00e0 son maternel courant s\u2019\u00e9coule vers ce terme divin de la fa\u00e7on la plus s\u00fbre, la plus compl\u00e8te, la plus rapide\u2026 Toute \u00e2me livr\u00e9e \u00e0 Marie marche et s\u2019\u00e9coule vers l\u2019Oc\u00e9an infini de l\u2019Amour\u00a0!&#8230; Le Rosaire, c\u2019est un encha\u00eenement d\u2019amour de Marie \u00e0 la Trinit\u00e9<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>\u00a0!\u00a0\u00bb<\/p>\n<p>Le Rosaire est donc l\u2019arme secr\u00e8te des enfants de Marie pour pr\u00e9parer le retour de J\u00e9sus. Il est l\u2019arme infaillible des derniers temps\u00a0: prenons conscience que nous avons entre les mains et dans cette pri\u00e8re du c\u0153ur \u00ab\u00a0une arme fatale, un laser imparable, une invincible douceur.\u00a0\u00bb En ce temps o\u00f9 p\u00e8se la terrible menace d\u2019une troisi\u00e8me et fatale guerre mondiale, le Rosaire est \u00ab\u00a0l\u2019arme des doux\u00a0\u00bb pour vaincre le plan de Satan vers l\u2019apocalypse nucl\u00e9aire\u00a0! Et vu la situation extr\u00eame o\u00f9 nous sommes arriv\u00e9s au Moyen orient ou en Ukraine, le Rosaire est notre premier engagement de pri\u00e8re intense pour la paix du monde\u00a0! Alors, n\u2019oublions pas \u00ab\u00a0l\u2019alerte\u00a0\u00bb que nous a donn\u00e9 Lucie de Fatima\u00a0:<\/p>\n<p>\u00ab\u00a0Depuis que la tr\u00e8s Sainte Vierge a donn\u00e9 une grande efficacit\u00e9 au chapelet, il n\u2019y a pas de probl\u00e8me mat\u00e9riel ou spirituel, national ou international, qui ne puisse \u00eatre r\u00e9solu par le chapelet et nos sacrifices\u00a0!\u00a0\u00bb<\/p>\n<p>+M Micka\u00ebl<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> T\u00e9moignages sur les Apparitions de Fatima, par le P\u00e8re De Marchi, Fatima, Edi\u00e7oes Misso\u00e9s Consolata, 2000, p.60.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> \u00ab\u00a0D\u2019apr\u00e8s ce que nous a dit Mr Marto, le p\u00e8re de Jacinta et Francisco\u2026 il semble que c\u2019est Francisco qui avait imagin\u00e9 la mani\u00e8re exp\u00e9ditive de se d\u00e9barrasser du chapelet\u00a0\u00bb, P\u00e8re De Marchi, <em>T\u00e9moignages sur les Apparitions de Fatima<\/em>, Edi\u00e7oes Missoes Consolata, 2000, p.56.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> P\u00e8re Vayssi\u00e8res, <em>Le Rosaire<\/em>, Traditions monastiques 2018, p.12-13.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Car o\u00f9 est ton tr\u00e9sor, l\u00e0 aussi sera ton c\u0153ur\u2026\u00a0\u00bb\u00a0 Matthieu 6,21 &nbsp; A l\u2019approche du 7 octobre, F\u00eate de Notre Dame du Rosaire, il est urgent d\u2019imiter le n\u00e9gociant de l\u2019Evangile\u00a0: \u00ab\u00a0Quand il a trouv\u00e9 une perle de grande valeur, il va vendre tout ce qu\u2019il poss\u00e8de et ach\u00e8te cette perle\u00a0!\u00a0\u00bb (Mt 13,45). Mais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[46,11],"tags":[],"class_list":["post-1529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-de-marie-mickael","category-prieres","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"Le Rosaire est l\u2019arme infaillible des derniers temps\u00a0: cette pri\u00e8re du c\u0153ur\u00a0est une arme fatale, un laser imparable, une invincible douceur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"Le Rosaire est l\u2019arme infaillible des derniers temps\u00a0: cette pri\u00e8re du c\u0153ur\u00a0est une arme fatale, un laser imparable, une invincible douceur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-04T15:55:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T16:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/09\/Vierge-Marie.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde\",\"datePublished\":\"2024-10-04T15:55:59+00:00\",\"dateModified\":\"2026-01-06T16:05:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/\"},\"wordCount\":913,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vierge-Marie.jpeg\",\"articleSection\":[\"Articles de Marie-Micka\u00ebl\",\"Prier\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/\",\"name\":\"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vierge-Marie.jpeg\",\"datePublished\":\"2024-10-04T15:55:59+00:00\",\"dateModified\":\"2026-01-06T16:05:14+00:00\",\"description\":\"Le Rosaire est l\u2019arme infaillible des derniers temps\u00a0: cette pri\u00e8re du c\u0153ur\u00a0est une arme fatale, un laser imparable, une invincible douceur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vierge-Marie.jpeg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Vierge-Marie.jpeg\",\"width\":320,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/10\\\/04\\\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"Le Rosaire est l\u2019arme infaillible des derniers temps\u00a0: cette pri\u00e8re du c\u0153ur\u00a0est une arme fatale, un laser imparable, une invincible douceur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"Le Rosaire est l\u2019arme infaillible des derniers temps\u00a0: cette pri\u00e8re du c\u0153ur\u00a0est une arme fatale, un laser imparable, une invincible douceur.","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2024-10-04T15:55:59+00:00","article_modified_time":"2026-01-06T16:05:14+00:00","og_image":[{"width":320,"height":427,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/09\/Vierge-Marie.jpeg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde","datePublished":"2024-10-04T15:55:59+00:00","dateModified":"2026-01-06T16:05:14+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/"},"wordCount":913,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/09\/Vierge-Marie.jpeg","articleSection":["Articles de Marie-Micka\u00ebl","Prier"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/","name":"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/09\/Vierge-Marie.jpeg","datePublished":"2024-10-04T15:55:59+00:00","dateModified":"2026-01-06T16:05:14+00:00","description":"Le Rosaire est l\u2019arme infaillible des derniers temps\u00a0: cette pri\u00e8re du c\u0153ur\u00a0est une arme fatale, un laser imparable, une invincible douceur.","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/09\/Vierge-Marie.jpeg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/09\/Vierge-Marie.jpeg","width":320,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/10\/04\/la-perle-precieuse-du-saint-rosaire-pour-la-paix-du-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"La perle pr\u00e9cieuse du Saint Rosaire pour la paix du monde"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1529"}],"version-history":[{"count":1,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1529\/revisions"}],"predecessor-version":[{"id":1531,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1529\/revisions\/1531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/1530"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}