{"id":1685,"date":"2024-11-15T15:50:48","date_gmt":"2024-11-15T15:50:48","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=1685"},"modified":"2026-01-06T16:04:49","modified_gmt":"2026-01-06T16:04:49","slug":"la-salette-laccueil-de-levenement","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/","title":{"rendered":"La Salette : l&rsquo;accueil de l&rsquo;\u00e9v\u00e8nement"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1685?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p>Tel est le r\u00e9cit des Bergers de La Salette (voir les articles des derni\u00e8res semaines). Leur t\u00e9moignage exhaustif montre qu&rsquo;il ne s&rsquo;agit ni d&rsquo;une le\u00e7on confi\u00e9e \u00e0 de simples perroquets, ni d&rsquo;une apparition mineure. En 1846, analphab\u00e8tes et ignorants du Fran\u00e7ais, pouvaient-ils en expliquer toute la port\u00e9e ! L&rsquo;apparition approuv\u00e9e et Mgr de Bruillard parti, pourquoi les avoir transform\u00e9s en simples marionnettes d&rsquo;exalt\u00e9s ou en illusionn\u00e9s r\u00e9duits \u00e0 l&rsquo;\u00e9loignement ? Un autre t\u00e9moin de l&rsquo;Apparition, plus lointain et moins entra\u00een\u00e9 \u00e0 sa suite sur le chemin du calvaire, aurait-il exist\u00e9 ?<br \/>\nVoici la vision de M. Le Beaumont, cultivateur du hameau des Chambons :<br \/>\nVers 3 h. 1\/2 le 19 septembre 1846 il se reposait, le dos tourn\u00e9 vers Corps, regardant ses b\u0153ufs. Il se sent pouss\u00e9 \u00e0 se retourner&#8230; au-dessus de Corps, il aper\u00e7ut un grand cercle de lumi\u00e8re tirant sur le rouge, il le contemple en extase : oh que c&rsquo;est beau ! &#8230; Puis un \u00e9clair part du c\u00f4t\u00e9 de la Salette, tirant sur le jaune. L&rsquo;\u00e9clair s&rsquo;approche du cercle. Le cercle s&rsquo;ouvre, l&rsquo;\u00e9clair entre dedans&#8230; Il regarde un moment : comme c&rsquo;est beau!&#8230; tout dispara\u00eet. III<br \/>\nLe cultivateur d\u00e9telle ses b\u0153ufs et rentre chez lui, litt\u00e9ralement muet de stupeur. Croyant \u00e0 un malaise, les siens le couchent jusqu&rsquo;\u00e0 ce qu&rsquo;il reprenne ses sens&#8230; Mais ce t\u00e9moin ne s&rsquo;est pas manifest\u00e9. C&rsquo;est une parente qui consigna son t\u00e9moignage, longtemps apr\u00e8s.<\/p>\n<h2>\nL&rsquo;accueil de l&rsquo;\u00e9v\u00e8nement<\/h2>\n<p>Aussit\u00f4t racont\u00e9 par les deux jeunes bergers, l&rsquo;\u00e9v\u00e9nement de la Salette frappa vivement les auditeurs : paysans du hameau des Ablandins qui n&rsquo;iront pas travailler aux champs le lendemain, dimanche, comme d&rsquo;habitude, et le vieux cur\u00e9 de la Salette qui en instruira aussit\u00f4t ses paroissiens en chaire.<\/p>\n<p>Deux semaines plus tard, l&rsquo;Abb\u00e9 M\u00e9lin, qui fait fonction d&rsquo;archipr\u00eatre \u00e0 Corps, avertit son \u00e9v\u00eaque de l&rsquo;\u00e9moi du peuple en exprimant son impression positive :<\/p>\n<p>\u00ab\u00a0Le r\u00e9cit de ces deux enfants a produit un effet extraordinaire dans les environs, m\u00eame chez les hommes. Je les ai interrog\u00e9s s\u00e9par\u00e9ment et chez moi, et sur les lieux m\u00eame[s] o\u00f9 je suis arriv\u00e9 apr\u00e8s quatre heures de marche p\u00e9nible ; les autorit\u00e9s les ont menac\u00e9[s] pour les faire taire ; on leur a offert de l&rsquo;argent pour leur faire dire le contraire de ce qu&rsquo;ils affirmaient, ni les menaces, ni, les promesses n&rsquo;ont pu faire varier leur langage ; ils disent toujours les m\u00eames choses et \u00e0 qui veut l&rsquo;entendre.<br \/>\nJe suis all\u00e9 tr\u00e8s lentement dans les informations que j&rsquo;ai pu prendre, je n&rsquo;ai rien pu d\u00e9couvrir qui d\u00e9note le moins du monde la supercherie ou le mensonge. La premi\u00e8re id\u00e9e de toute la contr\u00e9e a \u00e9t\u00e9 de faire b\u00e2tir un oratoire dans cet endroit [&#8230;]<br \/>\nL&rsquo;interpr\u00e9tation des fid\u00e8les a \u00e9t\u00e9 tout naturellement que c&rsquo;\u00e9tait la bonne M\u00e8re qui venait avertir le monde, avant que son Fils ne laisse tomber sur lui ses vengeances. Ma conviction personnelle, d&rsquo;apr\u00e8s tout ce que j&rsquo;ai pu recueillir de preuves, ne diff\u00e8re pas de celle des fid\u00e8les, et je crois que cet avertissement est une grande faveur du Ciel. Je n&rsquo;ai pas besoin d&rsquo;autre prodige pour croire, mon d\u00e9sir bien sinc\u00e8re, serait que le bon Dieu, dans sa mis\u00e9ricorde op\u00e9r\u00e2t quelque\u00a0 nouvelle merveille pour confirmer la premi\u00e8re.\u00a0\u00bb<\/p>\n<p>La nouvelle de l&rsquo;apparition se r\u00e9pandit vite , mais suscite bient\u00f4t de pr\u00e9occupantes oppositions, politiques et\/ou eccl\u00e9siastiques. L&rsquo;autorit\u00e9 dioc\u00e9saine met donc cinq ans \u00e0 l&rsquo;\u00e9tudier.<br \/>\nLes nombreux interrogatoires des deux bergers, pris s\u00e9par\u00e9ment puis confront\u00e9s, \u00e9tablirent le discours que la \u00ab\u00a0belle Dame\u00a0\u00bb leur adresse ensemble, en fran\u00e7ais puis en patois : le \u00ab\u00a0message public\u00a0\u00bb. Au terme de l&rsquo;enqu\u00eate, Rome fut consult\u00e9e, les l\u00e9gats de l&rsquo;\u00e9v\u00eaque de Grenoble remirent aussi en main propre au Pape Pie IX le \u00ab\u00a0message secret\u00a0\u00bb \u00e9crit et scell\u00e9 par chacun des t\u00e9moins. Apr\u00e8s quoi, par le mandement du 19 sept. 1851 , Mgr de Bruillard put d\u00e9clarer que : l&rsquo;apparition de la Tr\u00e8s Sainte Vierge \u00e0 deux bergers, le 19 septembre 1846 [&#8230;] porte en elle-m\u00eame tous les caract\u00e8res de la v\u00e9rit\u00e9, et que les fid\u00e8les sont fond\u00e9s \u00e0 la croire indubitable et certaine.<\/p>\n<p>Ce d\u00e9cret ne mit pas fin \u00e0 l&rsquo;incr\u00e9dulit\u00e9 de quelques membres du clerg\u00e9 local soutenus par l&rsquo;Archev\u00eaque de Lyon ou l&rsquo;\u00e9v\u00eaque de Gap. Devant le langage terre \u00e0 terre de la belle Dame, son vocabulaire plus bibliques que th\u00e9ologique, les esprits forts se faisaient sceptiques et le grand Lacordaire s&rsquo;exclamait : \u00ab\u00a0Absurde, ridicule, impossible\u00a0\u00bb !<br \/>\nTout en gardant au sens premier du message sa v\u00e9rit\u00e9 frappante, d&rsquo;autres penseurs retrouveront, \u00e0 travers le concret de la lettre et du geste, la \u00ab\u00a0grande nouvelle\u00a0\u00bb mariale adress\u00e9e au monde tout entier.<\/p>\n<p>Le message de Marie proclam\u00e9 sur la montagne d\u00e9borde son contexte imm\u00e9diat. L&rsquo;apparition a lieu l&rsquo;apr\u00e8s-midi du samedi 19 septembre 1846. Dans la liturgie, l&rsquo;heure \u00e9tait \u00e0 la<br \/>\np\u00e9nitence (des \u00ab\u00a0Quatre-Temps\u00a0\u00bb du d\u00e9but d\u00e9 l&rsquo;automne) : plus exactement, aux premi\u00e8res v\u00eapres de la F\u00eate de N.D. des Sept Douleurs c\u00e9l\u00e9br\u00e9e le lendemain.<\/p>\n<p><em>A suivre&#8230;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tel est le r\u00e9cit des Bergers de La Salette (voir les articles des derni\u00e8res semaines). Leur t\u00e9moignage exhaustif montre qu&rsquo;il ne s&rsquo;agit ni d&rsquo;une le\u00e7on confi\u00e9e \u00e0 de simples perroquets, ni d&rsquo;une apparition mineure. En 1846, analphab\u00e8tes et ignorants du Fran\u00e7ais, pouvaient-ils en expliquer toute la port\u00e9e ! L&rsquo;apparition approuv\u00e9e et Mgr de Bruillard parti, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1687,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[40,28,3],"tags":[],"class_list":["post-1685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apparitions-du-19eme-siecle","category-la-salette","category-revelations-pour-la-fin-des-temps","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Salette : l&#039;accueil de l&#039;\u00e9v\u00e8nement - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"Comment furent accueillies les apparitions de Notre-Dame \u00e0 la Salette par les autorit\u00e9s eccl\u00e9siastiques locales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Salette : l&#039;accueil de l&#039;\u00e9v\u00e8nement - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"Comment furent accueillies les apparitions de Notre-Dame \u00e0 la Salette par les autorit\u00e9s eccl\u00e9siastiques locales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-15T15:50:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T16:04:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/11\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1991\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"La Salette : l&rsquo;accueil de l&rsquo;\u00e9v\u00e8nement\",\"datePublished\":\"2024-11-15T15:50:48+00:00\",\"dateModified\":\"2026-01-06T16:04:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/\"},\"wordCount\":932,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg\",\"articleSection\":[\"Apparitions du 19\u00e8me si\u00e8cle\",\"La Salette\",\"R\u00e9v\u00e9lations pour la fin des temps\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/\",\"name\":\"La Salette : l'accueil de l'\u00e9v\u00e8nement - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg\",\"datePublished\":\"2024-11-15T15:50:48+00:00\",\"dateModified\":\"2026-01-06T16:04:49+00:00\",\"description\":\"Comment furent accueillies les apparitions de Notre-Dame \u00e0 la Salette par les autorit\u00e9s eccl\u00e9siastiques locales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg\",\"width\":1991,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/11\\\/15\\\/la-salette-laccueil-de-levenement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Salette : l&rsquo;accueil de l&rsquo;\u00e9v\u00e8nement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Salette : l'accueil de l'\u00e9v\u00e8nement - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"Comment furent accueillies les apparitions de Notre-Dame \u00e0 la Salette par les autorit\u00e9s eccl\u00e9siastiques locales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/","og_locale":"fr_FR","og_type":"article","og_title":"La Salette : l'accueil de l'\u00e9v\u00e8nement - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"Comment furent accueillies les apparitions de Notre-Dame \u00e0 la Salette par les autorit\u00e9s eccl\u00e9siastiques locales.","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2024-11-15T15:50:48+00:00","article_modified_time":"2026-01-06T16:04:49+00:00","og_image":[{"width":1991,"height":2560,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/11\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"La Salette : l&rsquo;accueil de l&rsquo;\u00e9v\u00e8nement","datePublished":"2024-11-15T15:50:48+00:00","dateModified":"2026-01-06T16:04:49+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/"},"wordCount":932,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/11\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg","articleSection":["Apparitions du 19\u00e8me si\u00e8cle","La Salette","R\u00e9v\u00e9lations pour la fin des temps"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/","name":"La Salette : l'accueil de l'\u00e9v\u00e8nement - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/11\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg","datePublished":"2024-11-15T15:50:48+00:00","dateModified":"2026-01-06T16:04:49+00:00","description":"Comment furent accueillies les apparitions de Notre-Dame \u00e0 la Salette par les autorit\u00e9s eccl\u00e9siastiques locales.","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/11\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/11\/Bois-Colombes_Vitrail_La_Salette-scaled.jpg","width":1991,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/11\/15\/la-salette-laccueil-de-levenement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"La Salette : l&rsquo;accueil de l&rsquo;\u00e9v\u00e8nement"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1685"}],"version-history":[{"count":1,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1685\/revisions"}],"predecessor-version":[{"id":1688,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1685\/revisions\/1688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/1687"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}