{"id":2052,"date":"2025-04-25T15:50:29","date_gmt":"2025-04-25T15:50:29","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=2052"},"modified":"2026-01-06T16:04:27","modified_gmt":"2026-01-06T16:04:27","slug":"le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/","title":{"rendered":"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2052?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p>[32] J&rsquo;ai dit que cette d\u00e9votion consiste \u00e0 se donner \u00e0 Marie en qualit\u00e9 d&rsquo;esclave. Il faut remarquer qu&rsquo;il y a trois sortes d&rsquo;esclavage.<\/p>\n<p>Le premier est l&rsquo;esclavage de la nature ; les hommes bons et mauvais sont esclaves de Dieu en cette mani\u00e8re.<\/p>\n<p>Le second, c&rsquo;est l&rsquo;esclavage de contrainte ; les d\u00e9mons et les damn\u00e9s sont les esclaves de Dieu en cette mani\u00e8re.<\/p>\n<p>Le troisi\u00e8me, c&rsquo;est l&rsquo;esclavage d&rsquo;amour et de volont\u00e9 ; et c&rsquo;est celui par lequel nous devons nous consacrer \u00e0 Dieu par Marie, de la mani\u00e8re la plus parfaite dont une cr\u00e9ature se puisse servir pour se donner \u00e0 son Cr\u00e9ateur.<\/p>\n<p>[33] Remarquez encore qu&rsquo;il y a bien de la diff\u00e9rence entre un serviteur et un esclave. Un serviteur veut des gages pour ses services; l&rsquo;esclave n&rsquo;en a point. Le serviteur est libre de quitter son ma\u00eetre quand il voudra et il ne le sert que pour un temps; l&rsquo;esclave ne le peut quitter justement, il lui est livr\u00e9 pour toujours. Le serviteur ne donne pas \u00e0 son ma\u00eetre droit de vie et de mort sur sa personne; l&rsquo;esclave se donne tout entier, en sorte que son ma\u00eetre pourrait le faire mourir sans qu&rsquo;il en f\u00fbt inqui\u00e9t\u00e9 par la justice.<\/p>\n<p>Mais il est ais\u00e9 de voir que l&rsquo;esclave de contrainte a la plus \u00e9troite des d\u00e9pendances, qui ne peut proprement convenir qu&rsquo;\u00e0 un homme envers son Cr\u00e9ateur. C&rsquo;est pourquoi les chr\u00e9tiens ne font point de tels esclaves; il n&rsquo;y a que les Turcs et les idol\u00e2tres qui en font de la sorte.<\/p>\n<p>[34] Heureuse et mille fois heureuse est l&rsquo;\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d&rsquo;esclave d&rsquo;amour, apr\u00e8s avoir secou\u00e9 par le bapt\u00eame l&rsquo;esclavage tyrannique du d\u00e9mon !<\/p>\n<p><em>A suivre\u2026<\/em><\/p>\n<p><a href=\"https:\/\/refugesdemarie.fr\/?p=1812&amp;preview=true\">Pour consulter le plan de l\u2019ouvrage, cliquer ici<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[32] J&rsquo;ai dit que cette d\u00e9votion consiste \u00e0 se donner \u00e0 Marie en qualit\u00e9 d&rsquo;esclave. Il faut remarquer qu&rsquo;il y a trois sortes d&rsquo;esclavage. Le premier est l&rsquo;esclavage de la nature ; les hommes bons et mauvais sont esclaves de Dieu en cette mani\u00e8re. Le second, c&rsquo;est l&rsquo;esclavage de contrainte ; les d\u00e9mons et les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saints","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34 - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"Heureuse et mille fois heureuse est l&#039;\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d&#039;esclave d&#039;amour !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34 - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"Heureuse et mille fois heureuse est l&#039;\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d&#039;esclave d&#039;amour !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-25T15:50:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T16:04:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2025\/03\/michelangetroispieta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34\",\"datePublished\":\"2025-04-25T15:50:29+00:00\",\"dateModified\":\"2026-01-06T16:04:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/\"},\"wordCount\":343,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/michelangetroispieta.jpg\",\"articleSection\":[\"Saints\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/\",\"name\":\"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34 - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/michelangetroispieta.jpg\",\"datePublished\":\"2025-04-25T15:50:29+00:00\",\"dateModified\":\"2026-01-06T16:04:27+00:00\",\"description\":\"Heureuse et mille fois heureuse est l'\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d'esclave d'amour !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/michelangetroispieta.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/michelangetroispieta.jpg\",\"width\":820,\"height\":432},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2025\\\/04\\\/25\\\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34 - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"Heureuse et mille fois heureuse est l'\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d'esclave d'amour !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/","og_locale":"fr_FR","og_type":"article","og_title":"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34 - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"Heureuse et mille fois heureuse est l'\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d'esclave d'amour !","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2025-04-25T15:50:29+00:00","article_modified_time":"2026-01-06T16:04:27+00:00","og_image":[{"width":820,"height":432,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2025\/03\/michelangetroispieta.jpg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34","datePublished":"2025-04-25T15:50:29+00:00","dateModified":"2026-01-06T16:04:27+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/"},"wordCount":343,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2025\/03\/michelangetroispieta.jpg","articleSection":["Saints"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/","name":"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34 - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2025\/03\/michelangetroispieta.jpg","datePublished":"2025-04-25T15:50:29+00:00","dateModified":"2026-01-06T16:04:27+00:00","description":"Heureuse et mille fois heureuse est l'\u00e2me lib\u00e9rale qui se consacre \u00e0 J\u00e9sus par Marie, en qualit\u00e9 d'esclave d'amour !","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2025\/03\/michelangetroispieta.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2025\/03\/michelangetroispieta.jpg","width":820,"height":432},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2025\/04\/25\/le-secret-de-marie-saint-louis-marie-grignion-de-montfort-n32-34\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"Le secret de Marie, Saint Louis-Marie Grignion de Montfort, n\u00b032-34"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2052"}],"version-history":[{"count":1,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2052\/revisions"}],"predecessor-version":[{"id":2054,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2052\/revisions\/2054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/2053"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}