{"id":2914,"date":"2026-01-23T15:45:45","date_gmt":"2026-01-23T15:45:45","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=2914"},"modified":"2026-01-19T07:54:58","modified_gmt":"2026-01-19T07:54:58","slug":"sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/","title":{"rendered":"S&rsquo;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&rsquo;est bien maintenant !"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2914?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><table role=\"presentation\" border=\"0\" width=\"100%\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td align=\"left\">\n<div>\n<div class=\"\">\n<p>On demanda un jour \u00e0 Mgr Fulton Sheen\u00a0(1) de d\u00e9crire le pouvoir du rosaire. \u00ab\u00a0<i>D\u00e9crire le pouvoir du rosaire\u00a0? Il n&rsquo;y a tout simplement pas de mots pour d\u00e9crire le pouvoir du rosaire\u00a0!<\/i>\u00a0\u00bb Il poursuivit en d\u00e9clarant\u00a0: \u00ab\u00a0<i>Le probl\u00e8me avec le monde d&rsquo;aujourd&rsquo;hui, c&rsquo;est qu&rsquo;on ne prie pas assez le rosaire\u00a0!<\/i>\u00a0\u00bb<\/p>\n<p>En 2004, un groupe de centres de grossesse pro-vie en Autriche s&rsquo;est engag\u00e9 \u00e0 prier le rosaire pendant plusieurs ann\u00e9es, \u00e0 la fois devant les centres d&rsquo;avortement et devant le Saint-Sacrement. Trois centres d&rsquo;avortement ont ferm\u00e9 en Autriche, dont l&rsquo;un a \u00e9t\u00e9 rachet\u00e9 par les militants pro-vie pour en faire un centre de gu\u00e9rison post-avortement. Lorsqu&rsquo;on lui a demand\u00e9 comment ces centres d&rsquo;avortement avaient pu fermer, le directeur des centres pro-vie a r\u00e9pondu\u00a0: \u00ab\u00a0<i>Gr\u00e2ce au pouvoir du rosaire<\/i>\u00a0\u00bb.<\/p>\n<p>Il existe de nombreuses choses qui sont puissantes et n\u00e9cessaires pour nous, Catholiques, en particulier la Sainte Messe, source et sommet de notre foi. Mais le rosaire est une simple m\u00e9ditation quotidienne sur la vie de Notre Seigneur, en compagnie de Notre Dame, et celle-ci nous a demand\u00e9 \u00e0 plusieurs reprises, ainsi que de nombreux Papes, de le r\u00e9citer. S&rsquo;il y a un moment o\u00f9 il faut se mettre \u00e0 prier le rosaire de tout son c\u0153ur, c&rsquo;est bien maintenant, alors que les menaces de l&rsquo;avortement jusqu&rsquo;au terme de la grossesse et l&rsquo;euthanasie sont sur le point de devenir loi.<\/p>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td align=\"right\">\n<div>\n<div class=\"\">\n<p style=\"text-align: left;\">Clare McCullough, 28 octobre 2025 (adapt\u00e9 d&rsquo;un article plus long) <a class=\"underline\" href=\"https:\/\/nl.mariedenazareth.com\/email_marketing_click.html?x=a62e&amp;co=dow&amp;lc=VqN5&amp;mc=c&amp;s=Oc&amp;u=H&amp;z=eEKuHUE&amp;\"> IndependentCatholicNews <\/a><\/p>\n<p style=\"text-align: left;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-2915\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg\" alt=\"\" width=\"201\" height=\"250\" \/><\/p>\n<p style=\"text-align: left;\">(1) Fulton John Sheen (1895-1979) est un pr\u00e9lat catholique am\u00e9ricain, \u00e9v\u00eaque auxiliaire de New York en 1951 puis \u00e9v\u00eaque r\u00e9sidentiel de Rochester en 1966, avant d&rsquo;\u00eatre promu archev\u00eaque in partibus en 1969.<\/p>\n<div class=\"kb0PBd LnCrMe\" data-snf=\"Vjbam\" data-sncf=\"0,1\">\n<div>\n<div class=\"uhHOwf ez24Df\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>On demanda un jour \u00e0 Mgr Fulton Sheen\u00a0(1) de d\u00e9crire le pouvoir du rosaire. \u00ab\u00a0D\u00e9crire le pouvoir du rosaire\u00a0? Il n&rsquo;y a tout simplement pas de mots pour d\u00e9crire le pouvoir du rosaire\u00a0!\u00a0\u00bb Il poursuivit en d\u00e9clarant\u00a0: \u00ab\u00a0Le probl\u00e8me avec le monde d&rsquo;aujourd&rsquo;hui, c&rsquo;est qu&rsquo;on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb En 2004, un groupe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prieres","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S&#039;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&#039;est bien maintenant ! - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"\u00ab\u00a0Le probl\u00e8me avec le monde d&#039;aujourd&#039;hui, c&#039;est qu&#039;on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb, disait Mgr Fulton John Sheen (1895-1979).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S&#039;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&#039;est bien maintenant ! - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0Le probl\u00e8me avec le monde d&#039;aujourd&#039;hui, c&#039;est qu&#039;on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb, disait Mgr Fulton John Sheen (1895-1979).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T15:45:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"201\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"S&rsquo;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&rsquo;est bien maintenant !\",\"datePublished\":\"2026-01-23T15:45:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/\"},\"wordCount\":318,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Mgr-Fulton-Sheen.jpeg\",\"articleSection\":[\"Prier\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/\",\"name\":\"S'il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c'est bien maintenant ! - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Mgr-Fulton-Sheen.jpeg\",\"datePublished\":\"2026-01-23T15:45:45+00:00\",\"description\":\"\u00ab\u00a0Le probl\u00e8me avec le monde d'aujourd'hui, c'est qu'on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb, disait Mgr Fulton John Sheen (1895-1979).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Mgr-Fulton-Sheen.jpeg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Mgr-Fulton-Sheen.jpeg\",\"width\":201,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/01\\\/23\\\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S&rsquo;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&rsquo;est bien maintenant !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S'il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c'est bien maintenant ! - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"\u00ab\u00a0Le probl\u00e8me avec le monde d'aujourd'hui, c'est qu'on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb, disait Mgr Fulton John Sheen (1895-1979).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/","og_locale":"fr_FR","og_type":"article","og_title":"S'il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c'est bien maintenant ! - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"\u00ab\u00a0Le probl\u00e8me avec le monde d'aujourd'hui, c'est qu'on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb, disait Mgr Fulton John Sheen (1895-1979).","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2026-01-23T15:45:45+00:00","og_image":[{"width":201,"height":250,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"S&rsquo;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&rsquo;est bien maintenant !","datePublished":"2026-01-23T15:45:45+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/"},"wordCount":318,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg","articleSection":["Prier"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/","name":"S'il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c'est bien maintenant ! - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg","datePublished":"2026-01-23T15:45:45+00:00","description":"\u00ab\u00a0Le probl\u00e8me avec le monde d'aujourd'hui, c'est qu'on ne prie pas assez le rosaire\u00a0!\u00a0\u00bb, disait Mgr Fulton John Sheen (1895-1979).","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/01\/Mgr-Fulton-Sheen.jpeg","width":201,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/01\/23\/sil-y-a-un-moment-ou-il-faut-prier-le-rosaire-de-tout-son-coeur-cest-bien-maintenant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"S&rsquo;il y a un moment o\u00f9 il faut prier le rosaire de tout son c\u0153ur, c&rsquo;est bien maintenant !"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2914"}],"version-history":[{"count":3,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2914\/revisions"}],"predecessor-version":[{"id":2918,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2914\/revisions\/2918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/2915"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}