{"id":2959,"date":"2026-02-13T15:55:24","date_gmt":"2026-02-13T15:55:24","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=2959"},"modified":"2026-02-04T07:44:13","modified_gmt":"2026-02-04T07:44:13","slug":"la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/","title":{"rendered":"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4)"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2959?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p style=\"text-align: center;\"><strong>La pri\u00e8re urgente de la Vierge \u00e0 Fatima !<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>4 \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>sa Protection du feu de l\u2019Enfer\u2026<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 <\/strong>Tel est <strong>le second cri vers son Fils Sauveur\u00a0! <\/strong>Et si Notre Dame de Fatima nous fait faire une telle pri\u00e8re, c\u2019est que les temps actuels sont <strong>\u00ab\u00a0dangereux\u00a0\u00bb \u00e0 l\u2019extr\u00eame\u00a0! <\/strong>L\u2019\u00e9volution soci\u00e9tale n\u2019a plus de limites et engendre une terrible d\u00e9gradation des m\u0153urs\u2026 Comment ne pas pressentir alors <strong>une influence d\u00e9moniaque de plus en plus dominante<\/strong>\u00a0? Elle est m\u00eame un signe de ralliement pour toute une jeunesse qui participe chaque ann\u00e9e au <strong>Hellfest (<\/strong>de Clisson pr\u00e8s de Nantes) \u00e0 travers une musique, des signes et des paroles d\u2019enfer\u00a0! De \u00ab\u00a0Iron Maiden \u00e0 S\u00e9pultura, en passant par D\u00e9icide\u00a0!&#8230;\u00a0\u00bb La c\u00e9l\u00e9bration de l\u2019ange des t\u00e9n\u00e8bres est librement affich\u00e9e\u00a0!<\/p>\n<p>L\u2019Eglise actuelle, \u00e0 part Saint Jean-Paul II<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, est elle bien <strong>silencieuse<\/strong> sur la pr\u00e9sence et l\u2019influence actuelle des d\u00e9mons qui orientent trop souvent les lois et les comportements de notre civilisation actuelle. Il est donc <strong>\u00ab\u00a0urgent\u00a0\u00bb <\/strong>de nous r\u00e9approprier la pl\u00e9nitude de notre foi catholique sur les fins derni\u00e8res\u00a0: n\u2019oublions jamais que chaque instant de notre vie avec ses choix et ses luttes en pr\u00e9pare une autre pour toujours\u00a0! Car \u00ab\u00a0au soir de notre vie, nous serons jug\u00e9s sur l\u2019amour<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>\u00a0\u00bb \u00e0 travers ce que le cat\u00e9chisme appelle un <strong>\u00ab\u00a0jugement particulier\u00a0\u00bb\u00a0<\/strong>:<\/p>\n<p><strong>\u00ab\u00a0La mort met fin \u00e0 la vie de l\u2019homme comme temps ouvert \u00e0 l\u2019accueil ou au rejet de la gr\u00e2ce divine manifest\u00e9e dans le Christ <\/strong>(2 Tm 1,9-10). <strong>Le Nouveau Testament parle du jugement principalement dans la perspective de la rencontre finale avec le Christ dans son second Av\u00e8nement, mais il affirme aussi \u00e0 plusieurs reprises la r\u00e9tribution imm\u00e9diate apr\u00e8s la mort de chacun en fonction de ses \u0153uvres et de sa foi\u2026 La parabole du pauvre Lazare et la parole du Christ en Croix au bon larron\u2026 <\/strong>(Lc 16,22 \/ Lc 23,43).<\/p>\n<p><strong>\u00ab\u00a0Chaque homme re\u00e7oit dans son \u00e2me immortelle sa r\u00e9tribution \u00e9ternelle d\u00e9s sa mort en un jugement particulier qui r\u00e9f\u00e8re sa vie au Christ, soit \u00e0 travers une purification, soit pour entrer imm\u00e9diatement dans la b\u00e9atitude du Ciel, soit pour se damner imm\u00e9diatement pour toujours\u00a0<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>!\u00a0\u00bb<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 <\/strong>Et le Concile Vatican II nous pr\u00e9vient avec la m\u00eame insistance sur le s\u00e9rieux de la vie sur terre :<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 \u00ab Ignorants du jour et de l\u2019heure, il faut que, suivant l\u2019Avertissement du Seigneur, nous restions \u00ab\u00a0vigilants\u00a0\u00bb pour m\u00e9riter, quand s\u2019ach\u00e8vera le cours unique de notre vie terrestre <\/strong>(He 2,27), <strong>d\u2019\u00eatre admis avec Lui aux noces et compt\u00e9s parmi les b\u00e9nis de Dieu <\/strong>(Mt 25,31-46), <strong>au lieu d\u2019\u00eatre, comme de mauvais et paresseux serviteurs <\/strong>(Mt 25,26) <strong>\u00e9cart\u00e9s par l\u2019ordre de Dieu vers le feu \u00e9ternel <\/strong>(Mt 25,41), <strong>vers ces t\u00e9n\u00e8bres du dehors o\u00f9 seront les pleurs et les grincements de dents <a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>\u2026\u00a0\u00bb <\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 <\/strong>Ces v\u00e9rit\u00e9s engagent notre vie et notre \u00e9ternit\u00e9 et il est urgent de nous les r\u00e9approprier pour <strong>fuir<\/strong> <strong>les illusions du monde<\/strong> et marcher sur le chemin de la conversion \u00e9vang\u00e9lique vers la vraie paix\u00a0! C\u2019est pourquoi la Vierge de Fatima nous tourne vers J\u00e9sus, notre Unique Sauveur\u00a0pour lui crier\u00a0:<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00ab\u00a0Pr\u00e9serve-nous du Feu de l\u2019Enfer\u00a0!\u00a0\u00bb<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0 <\/strong>Car m\u00eame chez beaucoup de catholiques, il y a une peur immature ou un refus secret d\u2019accueillir ces v\u00e9rit\u00e9s des <strong>\u00ab\u00a0fin derni\u00e8res\u00a0\u00bb<\/strong> qui font pourtant partie int\u00e9grante de la foi de l\u2019Eglise. Je me souviens de cette catholique rencontr\u00e9e \u00e0 Fatima lors d\u2019un p\u00e8lerinage\u00a0: elle me partageait sa joie de vivre ce p\u00e8lerinage \u00e0 l\u2019\u00e9cole des trois enfants de Fatima\u2026 puis tout \u00e0 coup changea de ton, en disant\u00a0qu\u2019elle faisait \u00ab\u00a0l\u2019impasse\u00a0\u00bb sur leur vision de l\u2019enfer qu\u2019elle n\u2019admettait pas\u00a0! Or, <strong>la foi catholique est une comme la Tunique de J\u00e9sus<\/strong> (Jn 19,23-24) et l\u2019on ne peut \u00ab\u00a0exclure\u00a0\u00bb une v\u00e9rit\u00e9 sans mettre en p\u00e9ril l\u2019ensemble<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>\u2026<\/p>\n<p>Il faut donc ici <strong>m\u00e9diter un instant <\/strong><a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a> sur la vision du 13 juillet 1917 donn\u00e9e aux 3 enfants de Fatima. \u00a0La Vierge y ouvre par un geste <strong>la porte de l\u2019Enfer<\/strong>\u00a0:<\/p>\n<p><strong>\u00ab\u00a0La Vierge ouvrit de nouveau les mains, comme les deux derniers mois. Le reflet parut p\u00e9n\u00e9trer la terre et nous v\u00eemes \u00ab\u00a0un oc\u00e9an de feu\u00a0\u00bb, et plong\u00e9s dans ce feu, les d\u00e9mons et les \u00e2mes, comme s\u2019ils \u00e9taient des braises transparentes, noires ou bronz\u00e9es, ayant des formes humaines\u2026 Elles flottaient dans l\u2019incendie, soulev\u00e9es par les flammes qui sortaient d\u2019elles-m\u00eames avec des nuages de fum\u00e9e, tombant de tous c\u00f4t\u00e9s, semblables \u00e0 la retomb\u00e9e des \u00e9tincelles dans les grands incendies, sans poids ni \u00e9quilibre, avec des cris et des g\u00e9missements de douleurs et de d\u00e9sespoir qui horrifiaient et faisaient trembler de frayeur\u00a0!&#8230;<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les d\u00e9mons se distinguaient par leurs formes horribles et r\u00e9pugnantes d\u2019animaux effrayants et inconnus, mais transparents comme des charbons noirs embras\u00e9s\u2026\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Effray\u00e9s, comme pour demander secours, nous avons lev\u00e9s les yeux vers Notre Dame qui nous avait promis de nous emmener au Ciel\u2026 Autrement, dit Lucie, je crois que nous serions morts d\u2019\u00e9pouvante et de peur\u00a0!\u00a0\u00bb<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0 <\/strong>Cette terrible vision bouleversera \u00e0 jamais la vie, la foi et la pri\u00e8re des enfants de Fatima, en particulier celle de <strong>la petite Jacinta<\/strong>\u00a0: elle va devenir un t\u00e9moin unique de l\u2019urgence du salut\u00a0! <strong>Elle qui aimait tant jouer va \u00a0maintenant\u00a0\u00ab\u00a0jouer\u00a0\u00bb toute sa vie pour sauver les p\u00e9cheurs\u00a0de l\u2019enfer ! <\/strong><\/p>\n<p>En conclusion\u00a0: retenons que cette vision \u00a0de l\u2019Enfer donne le vrai sens des combats de ce monde\u00a0: <strong>elle nous d\u00e9couvre de quelle horreur \u00e9ternelle \u00ab\u00a0J\u00e9sus est venu nous sauver\u00a0! \u00bb\u2026 Nous touchons l\u00e0 le centre profond du message de Notre Dame de Fatima qui nous a fait cette puissante promesse\u00a0: \u00ab\u00a0A la fin, mon C\u0153ur Immacul\u00e9 triomphera\u00a0!\u00a0\u00bb <\/strong><\/p>\n<p style=\"text-align: right;\"><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 +Marie-Micka\u00ebl <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Voir ses Audiences du mercredi sur les \u00ab\u00a0fins derni\u00e8res\u00a0: la vie, la mort, le Ciel, le purgatoire et l\u2019l\u2019enfer\u00a0\u00bb de juillet 1999.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Saint Jean de la Croix, Avisos 57.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Cat\u00e9chisme de l\u2019Eglise catholique, 1021 \u2013 1022.<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Concile Vatican II, <em>Lumen gentium, <\/em>48.<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Cela nous invite aussi \u00e0 prier pour \u00ab\u00a0l\u2019Unit\u00e9 des Chr\u00e9tiens\u00a0\u00bb dans la v\u00e9rit\u00e9 de la foi\u2026<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Pour un approfondissement des \u00ab\u00a0Fins derni\u00e8res\u00a0\u00bb sur Le Ciel, le Purgatoire et l\u2019Enfer, je renvoie \u00e0 mes m\u00e9ditations der derniers mois\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pri\u00e8re urgente de la Vierge \u00e0 Fatima ! 4 \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb \u00a0\u00a0\u00a0\u00a0 Tel est le second cri vers son Fils Sauveur\u00a0! Et si Notre Dame de Fatima nous fait faire une telle pri\u00e8re, c\u2019est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[46,31],"tags":[],"class_list":["post-2959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-de-marie-mickael","category-fatima","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4) - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"A Fatima, la Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4) - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"A Fatima, la Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T15:55:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/02\/13-juillet-17-ss-texte-300x198-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4)\",\"datePublished\":\"2026-02-13T15:55:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/\"},\"wordCount\":1140,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13-juillet-17-ss-texte-300x198-1.jpg\",\"articleSection\":[\"Articles de Marie-Micka\u00ebl\",\"Fatima\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/\",\"name\":\"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4) - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13-juillet-17-ss-texte-300x198-1.jpg\",\"datePublished\":\"2026-02-13T15:55:24+00:00\",\"description\":\"A Fatima, la Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13-juillet-17-ss-texte-300x198-1.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13-juillet-17-ss-texte-300x198-1.jpg\",\"width\":300,\"height\":198},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/13\\\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4) - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"A Fatima, la Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/","og_locale":"fr_FR","og_type":"article","og_title":"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4) - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"A Fatima, la Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2026-02-13T15:55:24+00:00","og_image":[{"width":300,"height":198,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/02\/13-juillet-17-ss-texte-300x198-1.jpg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4)","datePublished":"2026-02-13T15:55:24+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/"},"wordCount":1140,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/02\/13-juillet-17-ss-texte-300x198-1.jpg","articleSection":["Articles de Marie-Micka\u00ebl","Fatima"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/","name":"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4) - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/02\/13-juillet-17-ss-texte-300x198-1.jpg","datePublished":"2026-02-13T15:55:24+00:00","description":"A Fatima, la Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026\u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/02\/13-juillet-17-ss-texte-300x198-1.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2026\/02\/13-juillet-17-ss-texte-300x198-1.jpg","width":300,"height":198},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/13\/la-priere-urgente-de-la-vierge-a-fatima-la-vierge-nous-fait-demander-a-jesus-sa-protection-du-feu-de-lenfer-preserve-nous-du-feu-de-lenfer-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"La pri\u00e8re urgente de la Vierge \u00e0 Fatima \u2013 La Vierge nous fait demander \u00e0 J\u00e9sus sa Protection du feu de l\u2019Enfer\u2026 \u00ab Pr\u00e9serve-nous du feu de l\u2019Enfer ! \u00bb (4)"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2959"}],"version-history":[{"count":1,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2959\/revisions"}],"predecessor-version":[{"id":2961,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2959\/revisions\/2961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/2960"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}