{"id":2978,"date":"2026-02-06T15:40:47","date_gmt":"2026-02-06T15:40:47","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=2978"},"modified":"2026-02-04T17:27:53","modified_gmt":"2026-02-04T17:27:53","slug":"messages-donnes-a-gisella-cardia-en-janvier-2026","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/","title":{"rendered":"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2978?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><h2>Message de la Reine du Rosaire donn\u00e9 \u00e0 Gisella, le 3 janvier 2026<\/h2>\n<p>Chers enfants, merci d&rsquo;\u00eatre ici en pri\u00e8re et de vous agenouiller. Enfants b\u00e9nis, soyez forts pour ce qui va arriver ; vous devez \u00eatre pr\u00eats, pr\u00eats dans vos c\u0153urs et dans vos \u00e2mes. Pensez-vous que ce monde soit sans la lumi\u00e8re du Christ ? Il n&rsquo;en est rien, sinon vous ne seriez plus dans la foi et la pri\u00e8re. Quand de mauvaises choses arrivent, vous pensez : \u00ab O\u00f9 est Dieu ? \u00bb Mais en ces moments-l\u00e0, Il est l\u00e0, essayant de toucher votre c\u0153ur et de vous appeler \u00e0 la conversion. Il m&rsquo;a envoy\u00e9e sur terre pour vous avertir des dangers qui vous guettent, mais beaucoup rejettent mon conseil, moi, la M\u00e8re de J\u00e9sus et votre M\u00e8re. Vous vivez pire que Sodome et Gomorrhe, mais je veux que vous soyez sauv\u00e9s, et c&rsquo;est pourquoi je vous le demande : convertissez-vous maintenant ! N&rsquo;attendez pas la lumi\u00e8re qui est sur vous ! \u00c0 ce moment-l\u00e0, croyants et non-croyants ressentiront le feu int\u00e9rieur ; certains comprendront, d&rsquo;autres non. C&rsquo;est l&rsquo;acte ultime de Mis\u00e9ricorde. Mes enfants, pleurez et lamentez-vous, mais gardez espoir\u00a0: tout concourra \u00e0 votre seul bien. Aimez Dieu, car c\u2019est seulement aupr\u00e8s de Lui que vous trouverez la paix. Maintenant, je vous b\u00e9nis au nom du P\u00e8re, du Fils et du Saint-Esprit. Qu\u2019aujourd\u2019hui, une pluie de gr\u00e2ces vous enveloppe.<\/p>\n<h2>Message de la Reine du Rosaire donn\u00e9 \u00e0 Gisella, le 10 janvier 2026<\/h2>\n<p>Mes enfants, merci d&rsquo;\u00eatre ici en pri\u00e8re et merci de vous agenouiller. Mes enfants, je suis ici aujourd&rsquo;hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j&rsquo;aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde. Mes enfants, m\u00eame si vous avez commis de nombreuses erreurs dans votre vie, revenez \u00e0 Dieu, et j&rsquo;interc\u00e9derai aupr\u00e8s de mon Fils pour vous. Je suis le pont entre le ciel et la terre. Si Judas \u00e9tait venu se r\u00e9fugier dans mon c\u0153ur, il aurait \u00e9t\u00e9 pardonn\u00e9, mais au lieu de cela, il a choisi de se donner la mort ! Je vous dis cela afin que vous compreniez que tout p\u00e9ch\u00e9 peut \u00eatre pardonn\u00e9 par la confession. Mon Fils J\u00e9sus s&rsquo;en r\u00e9jouira et pleurera non de douleur, mais de joie, car une \u00e2me a \u00e9t\u00e9 retrouv\u00e9e ! N&rsquo;ayez pas peur, n&rsquo;ayez pas honte, la puissance de Dieu est grande. Je vous laisse maintenant avec ma Sainte B\u00e9n\u00e9diction, au nom du P\u00e8re, du Fils et du Saint-Esprit.<\/p>\n<p>Merci de m&rsquo;avoir re\u00e7ue.<\/p>\n<h2>Message de la Reine du Rosaire donn\u00e9 \u00e0 Gisella, le 13 janvier 2025<\/h2>\n<p>Mes enfants, merci d&rsquo;avoir r\u00e9pondu \u00e0 l&rsquo;appel que j&rsquo;ai lanc\u00e9 dans vos c\u0153urs. Mes enfants, j&#8217;emploie souvent des expressions comme \u00ab\u00a0Fatima est sur vous, elle est imminente\u00a0\u00bb. Cela cr\u00e9e un probl\u00e8me de compr\u00e9hension\u00a0: quand tout ce qui a \u00e9t\u00e9 pr\u00e9dit se produira-t-il\u00a0? Mes enfants, j&rsquo;ai essay\u00e9 de vous pr\u00e9parer durant ces ann\u00e9es, en vous expliquant ce qui allait arriver, mais vous cherchez des dates pr\u00e9cises. Je vous dis plut\u00f4t\u00a0: soyez pr\u00eats, et surtout, gardez vos c\u0153urs pr\u00eats. Mes enfants, tenez-vous pr\u00eats comme de vrais soldats\u00a0; vivez chaque jour comme si c&rsquo;\u00e9tait le dernier. Mes enfants, ne voyez-vous pas les guerres se propager, le temps n&rsquo;a plus de saisons, les tremblements de terre se font sentir avec une force croissante, les volcans entrent en \u00e9ruption partout dans le monde et la guerre est omnipr\u00e9sente\u00a0? Que voulez-vous voir de plus\u00a0? Le diable vous pousse \u00e0 continuer de vivre dans le p\u00e9ch\u00e9 et la frivolit\u00e9\u00a0; parfois, vous l&rsquo;\u00e9coutez encore davantage et vous vous laissez entra\u00eener dans le bourbier du p\u00e9ch\u00e9. Je vous b\u00e9nis maintenant, au nom du P\u00e8re, du Fils et du Saint-Esprit.<\/p>\n<h2>Message de la Reine du Rosaire, adress\u00e9 \u00e0 Gisella, le 17 janvier 2026.<\/h2>\n<p>Mes enfants, merci de votre union dans la pri\u00e8re et d&rsquo;avoir entendu l&rsquo;appel de mes c\u0153urs. Mes enfants b\u00e9nis, ayez foi, cette foi in\u00e9branlable qui est votre seul salut. Se confier \u00e0 Dieu, c&rsquo;est avoir la force d&rsquo;accomplir tout ce qu&rsquo;il faut, m\u00eame quand tout semble impossible. Mes enfants, tout ne se d\u00e9roule pas toujours comme pr\u00e9vu, et si vous ne laissez pas Dieu agir, tout deviendra difficile car certains \u00e9v\u00e9nements \u00e9chapperont \u00e0 votre contr\u00f4le. Mes enfants, lorsque l&rsquo;ange m&rsquo;a annonc\u00e9 ma maternit\u00e9, j&rsquo;\u00e9tais perdue et effray\u00e9e. Je ne pouvais rien faire d&rsquo;autre que croire, et c&rsquo;est gr\u00e2ce \u00e0 la foi que j&rsquo;ai accompli la volont\u00e9 de Dieu. Je n&rsquo;ai pas agi avec amertume, mais j&rsquo;ai dit oui ; vous devez faire de m\u00eame et ne d\u00e9sesp\u00e9rez pas. Je vous laisse maintenant avec ma b\u00e9n\u00e9diction maternelle au nom du P\u00e8re, du Fils et du Saint-Esprit.<\/p>\n<h2>Message de J\u00e9sus \u00e0 Gisella, le 20 janvier 2026<\/h2>\n<p>Mes bien-aim\u00e9s et mes fr\u00e8res, merci de prier. Vous ne voyez pas combien le monde a chang\u00e9 ! Rien ne redeviendra comme avant si l&rsquo;humanit\u00e9 ne m&rsquo;\u00e9coute pas. Mes enfants, vous tous, ou presque, vous me demandez des signes. Quand j&rsquo;\u00e9tais sur terre, j&rsquo;en ai donn\u00e9 beaucoup, mais beaucoup ont rejet\u00e9 ce don. L&rsquo;histoire se r\u00e9p\u00e8te ! Je donne tant de signes \u00e0 l&rsquo;humanit\u00e9, et pourtant ils ne sont pas accept\u00e9s, ils sont ridiculis\u00e9s, insult\u00e9s. Ma s\u0153ur, tu t&rsquo;efforces tant d&rsquo;expliquer que sans moi, il ne peut y avoir d&rsquo;ordre ! Et qu&rsquo;as-tu re\u00e7u ? Souviens-toi que le don demeure en toi, et mon m\u00e9pris en eux. J&rsquo;aime tant ceux qui me cherchent et veulent me conna\u00eetre ! Je vous laisse avec la paix du c\u0153ur et dans vos foyers.<\/p>\n<p>Votre J\u00e9sus<\/p>\n<h2>Message de J\u00e9sus, 24 janvier 2026<\/h2>\n<p>Mes enfants, priez le Saint Rosaire avec ferveur. Mes enfants, priez pour le communisme, qui semble endormi mais qui s&rsquo;\u00e9veillera avec toute sa puissance. Voyez-vous, en ce moment m\u00eame, je vais visiter mes chers pr\u00eatres, mes fils et fr\u00e8res bien-aim\u00e9s. Combien de fois leur demande-je de sauver des \u00e2mes, mais peu sont dispos\u00e9s \u00e0 le faire. Ils pensent souvent \u00e0 eux-m\u00eames, \u00e0 leurs souffrances humaines, mais ils ne r\u00e9alisent pas que je suis l\u00e0, pr\u00eat \u00e0 leur donner tout ce dont ils ont besoin ; ils doivent m&rsquo;amener des \u00e2mes. Combien de pr\u00eatres s&rsquo;\u00e9loignent de mes enfants bien-aim\u00e9s, sceptiques et hypocrites, ce qui me cause tant de souffrance ! Ils ne se demandent pas pourquoi j&rsquo;ai choisi ces \u00e2mes comme messagers. Je vous demande de ne pas boire la coupe du plaisir jusqu&rsquo;au bout, mais d&rsquo;aimer la Croix et la souffrance pour moi, afin de suivre le chemin de la saintet\u00e9. Ayez du courage et ne soyez pas insens\u00e9s ; renouvelez vos v\u0153ux. Parlez de moi et pr\u00eachez l&rsquo;\u00c9vangile. Priez pour l\u2019\u00c9glise, qui traverse sa Passion, et pour ces enfants bien-aim\u00e9s qui croient davantage en la science qu\u2019en Moi, l\u2019unique Sauveur. Je vous le demande encore\u00a0: n\u2019offensez pas ma M\u00e8re, Elle qui est la seule apr\u00e8s Moi\u00a0; aimez-la et honorez-la. La paix du monde repose sur la saintet\u00e9 de ses enfants et de l\u2019\u00c9glise. Je vous donne ma paix,<\/p>\n<p>Votre J\u00e9sus.<\/p>\n<h2>Message de la Reine du Rosaire donn\u00e9 \u00e0 Gisella le 27 janvier 2026<\/h2>\n<p>Mes enfants, mes chers amours, merci de vous unir dans la pri\u00e8re et d&rsquo;accueillir mon appel dans vos c\u0153urs. Mes enfants, je sens vos c\u0153urs battre \u00e0 l&rsquo;unisson\u00a0; sentez ma pr\u00e9sence\u00a0! Comme je d\u00e9sire ardemment vous embrasser tous avec amour, mais vous avez le libre arbitre et c&rsquo;est \u00e0 vous de prendre cette d\u00e9cision\u00a0; nul ne pourra violer votre c\u0153ur et votre \u00e2me. Mes enfants, c&rsquo;est un temps de gr\u00e2ce\u00a0! Vous recevrez de nombreuses gr\u00e2ces, moins nombreuses que vous ne l&rsquo;imaginez, moins \u00e9clatantes, mais de petites gr\u00e2ces que Dieu vous accorde chaque jour. Je vous le demande\u00a0: soyez capables de voir, de croire et d&rsquo;aimer Dieu. Je vous laisse maintenant avec ma b\u00e9n\u00e9diction maternelle, au nom du P\u00e8re, du Fils et du Saint-Esprit.<\/p>\n<h2>Message de J\u00e9sus \u00e0 Gisella, le 31 janvier 2026.<\/h2>\n<p>Mes enfants,<\/p>\n<p>restez fermes et confiants comme des enfants lorsque vous m&rsquo;invoquez, et je vous guiderai sur le chemin qui m\u00e8ne \u00e0 mon Royaume. Je prot\u00e9gerai tous ceux qui ont une confiance totale en mon amour et en ma sainte volont\u00e9. J&rsquo;interviendrai de toute ma puissance pour an\u00e9antir mes ennemis et r\u00e9pandre la v\u00e9rit\u00e9 afin que le monde nouveau soit habit\u00e9 par tous les enfants de Dieu. Convertissez-vous, mes enfants ! La pers\u00e9cution touchera tous les vrais chr\u00e9tiens. Restez spirituellement vigilants ; le choix vous appartient. Mes enfants, bient\u00f4t un grand schisme se produira au sein de l&rsquo;\u00c9glise. Ob\u00e9issez \u00e0 ma loi et n&rsquo;oubliez pas que le C\u0153ur de ma M\u00e8re triomphera. Je vous b\u00e9nis maintenant au nom du P\u00e8re, en mon Tr\u00e8s Saint Nom et au nom du Saint-Esprit.<\/p>\n<p>Votre J\u00e9sus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Message de la Reine du Rosaire donn\u00e9 \u00e0 Gisella, le 3 janvier 2026 Chers enfants, merci d&rsquo;\u00eatre ici en pri\u00e8re et de vous agenouiller. Enfants b\u00e9nis, soyez forts pour ce qui va arriver ; vous devez \u00eatre pr\u00eats, pr\u00eats dans vos c\u0153urs et dans vos \u00e2mes. Pensez-vous que ce monde soit sans la lumi\u00e8re du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[38],"tags":[],"class_list":["post-2978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trevignano","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026 - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"Je suis ici aujourd&#039;hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j&#039;aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026 - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"Je suis ici aujourd&#039;hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j&#039;aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T15:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/06\/Trevignano-image-4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026\",\"datePublished\":\"2026-02-06T15:40:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/\"},\"wordCount\":1573,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Trevignano-image-4.webp\",\"articleSection\":[\"Trevignano Romano\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/\",\"name\":\"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026 - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Trevignano-image-4.webp\",\"datePublished\":\"2026-02-06T15:40:47+00:00\",\"description\":\"Je suis ici aujourd'hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j'aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Trevignano-image-4.webp\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Trevignano-image-4.webp\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2026\\\/02\\\/06\\\/messages-donnes-a-gisella-cardia-en-janvier-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026 - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"Je suis ici aujourd'hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j'aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026 - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"Je suis ici aujourd'hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j'aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde.","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2026-02-06T15:40:47+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/06\/Trevignano-image-4.webp","type":"image\/webp"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026","datePublished":"2026-02-06T15:40:47+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/"},"wordCount":1573,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/06\/Trevignano-image-4.webp","articleSection":["Trevignano Romano"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/","name":"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026 - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/06\/Trevignano-image-4.webp","datePublished":"2026-02-06T15:40:47+00:00","description":"Je suis ici aujourd'hui comme la M\u00e8re de la Mis\u00e9ricorde. Oh ! combien j'aime les p\u00e9nitents, ceux qui demandent pardon \u00e0 Dieu, ceux qui implorent sa Mis\u00e9ricorde.","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/06\/Trevignano-image-4.webp","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/06\/Trevignano-image-4.webp","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2026\/02\/06\/messages-donnes-a-gisella-cardia-en-janvier-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"Messages donn\u00e9s \u00e0 Gisella Cardia en janvier 2026"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2978"}],"version-history":[{"count":2,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2978\/revisions"}],"predecessor-version":[{"id":2980,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2978\/revisions\/2980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/1278"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}