{"id":737,"date":"2023-12-01T16:57:49","date_gmt":"2023-12-01T16:57:49","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=737"},"modified":"2026-01-06T16:05:57","modified_gmt":"2026-01-06T16:05:57","slug":"marie-est-la","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/","title":{"rendered":"Marie est l\u00e0&#8230;"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/737?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p style=\"text-align: center;\"><strong>\u00ab\u00a0Je ne savais que mon Chapelet\u2026\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Sainte Bernadette de Lourdes<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0 <\/strong>\u00a0\u00a0\u00a0Je reviens juste de quelques jours de silence et de pri\u00e8re \u00e0 Lourdes. Et en m\u00e9ditant le Rosaire quotidien, la densit\u00e9 spirituelle et gestuelle de la premi\u00e8re Apparition de la Vierge \u00e0 Bernadette m\u2019a v\u00e9ritablement saut\u00e9 aux yeux comme une \u00e9vidence\u00a0: en effet, n\u2019est-il pas r\u00e9v\u00e9l\u00e9 ici, sans bruit de paroles, le secret du c\u0153ur de Bernadette<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> ? Oui, d\u00e8s le d\u00e9but de l\u2019Apparition, elle pose un geste qui en dit long sur le tr\u00e9sor humble et cach\u00e9 de sa vie chr\u00e9tienne : \u00ab Je mis la main \u00e0 la poche et je r\u00e9citais mon chapelet, ayant toujours cette Dame devant les yeux \u2026 \u00bb Telle est la premi\u00e8re v\u00e9rit\u00e9 de son \u00ab r\u00e9flexe marial \u00bb !<\/p>\n<p>Ainsi, comme \u00e0 Lourdes, il nous faut avoir aussi dans nos vies le \u00ab\u00a0r\u00e9flexe marial\u00a0\u00bb de la petite Bernadette. Face \u00e0 l\u2019envahissement bruyant et dispersant de notre monde actuel si agressif, il nous faut tenir et prier notre chapelet dans le m\u00e9tro ou dans la rue\u00a0: Marie notre M\u00e8re est toujours l\u00e0, \u00e0 veiller sur nous\u2026 et la pri\u00e8re du Chapelet est un merveilleux \u00e9veil \u00e0 cette pr\u00e9sence de la Vierge\u00a0qui vient \u00ab\u00a0prier\u00a0\u00bb avec nous\u00a0! Voil\u00e0 pourquoi, mine de rien, la premi\u00e8re Apparition de Marie nous r\u00e9v\u00e8le le grand secret de sa Pr\u00e9sence silencieuse.<\/p>\n<p>Alors ouvrons les yeux et le c\u0153ur sur cette premi\u00e8re rencontre du 11 f\u00e9vrier 1858\u00a0:<\/p>\n<p>Tout commence par une d\u00e9marche de l\u2019humble quotidien\u00a0: accompagn\u00e9e de sa s\u0153ur Toinette et d\u2019une amie, Bernadette se rend \u00e0 Massabielle<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> pour ramasser du bois mort au bord du Gave. Tout est calme en ce lieu quand, soudain, advient \u00ab\u00a0comme un coup de vent\u00a0\u00bb\u00a0! Elle tourne alors les yeux vers la Grotte et voit appara\u00eetre une Dame dans une douce lumi\u00e8re\u00a0:<\/p>\n<p>\u00ab\u00a0J\u2019aper\u00e7us une Dame v\u00eatue de blanc\u00a0: elle portait une robe blanche, un voile blanc \u00e9galement, une ceinture bleue, une rose jaune sur chaque pied\u2026\u00a0\u00bb<\/p>\n<p>A cet instant, Bernadette t\u00e9moigne de cette premi\u00e8re Apparition\u00a0: \u00ab\u00a0Je voulus faire le signe de la Croix avec mon chapelet, mais je ne pus porter la main jusqu\u2019au front\u2026 elle m\u2019est tomb\u00e9e\u00a0! La vision fit le signe de la Croix. Le grand saisissement que j\u2019\u00e9prouvais disparut. Je me mis \u00e0 genoux et je dis mon chapelet en pr\u00e9sence de la belle Dame. La vision faisait courir les grains du sien, mais elle ne remuait pas les l\u00e8vres. Quand j\u2019eus fini mon chapelet\u2026 Elle disparut.\u00a0\u00bb Ces instants resteront grav\u00e9s \u00e0 jamais en son c\u0153ur<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>\u2026<\/p>\n<p>Vision riche d\u2019enseignement pour notre chapelet quotidien : Marie prie avec nous et nous enveloppe de sa tendresse : c\u2019est l\u2019autre v\u00e9rit\u00e9 du \u00ab r\u00e9flexe marial \u00bb ! Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle ! Tel est le secret si simple de la premi\u00e8re Apparition de Lourdes o\u00f9 la r\u00e9citation du chapelet ouvre les yeux de notre foi sur sa Pr\u00e9sence : M\u00e8re attentive \u00e0 chaque instant de nos vies\u2026 Alors, \u00e9coutons un des plus beaux conseils de cette ch\u00e8re Bernadette : \u00ab Mettez-vous dans le C\u0153ur de Marie, et restez-y ! Faites-en votre demeure sur la terre\u2026 \u00bb<\/p>\n<p style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0+M-Micka\u00ebl<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Bernadette vient d\u2019avoir 14 ans le 7 janvier 1858.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Ce mot signifie \u00ab\u00a0vieille pierre\u00a0\u00bb en bigourdan.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> \u00ab\u00a0Que j\u2019aime \u00e0 me rappeler ces doux moments pass\u00e9s sous vos yeux pleins de bont\u00e9 et de mis\u00e9ricorde pour nous\u00a0!\u00a0\u00bb Carnet Reine du Ciel, 12 mai 1866.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Je ne savais que mon Chapelet\u2026\u00a0\u00bb Sainte Bernadette de Lourdes &nbsp; \u00a0 \u00a0\u00a0\u00a0Je reviens juste de quelques jours de silence et de pri\u00e8re \u00e0 Lourdes. Et en m\u00e9ditant le Rosaire quotidien, la densit\u00e9 spirituelle et gestuelle de la premi\u00e8re Apparition de la Vierge \u00e0 Bernadette m\u2019a v\u00e9ritablement saut\u00e9 aux yeux comme une \u00e9vidence\u00a0: en effet, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[40,46,30,3],"tags":[],"class_list":["post-737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apparitions-du-19eme-siecle","category-articles-de-marie-mickael","category-lourdes","category-revelations-pour-la-fin-des-temps","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marie est l\u00e0... - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marie est l\u00e0... - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-01T16:57:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T16:05:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/12\/20231127_170021-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1298\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"Marie est l\u00e0&#8230;\",\"datePublished\":\"2023-12-01T16:57:49+00:00\",\"dateModified\":\"2026-01-06T16:05:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/\"},\"wordCount\":614,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20231127_170021-scaled.jpg\",\"articleSection\":[\"Apparitions du 19\u00e8me si\u00e8cle\",\"Articles de Marie-Micka\u00ebl\",\"Lourdes\",\"R\u00e9v\u00e9lations pour la fin des temps\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/\",\"name\":\"Marie est l\u00e0... - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20231127_170021-scaled.jpg\",\"datePublished\":\"2023-12-01T16:57:49+00:00\",\"dateModified\":\"2026-01-06T16:05:57+00:00\",\"description\":\"Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20231127_170021-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/20231127_170021-scaled.jpg\",\"width\":1298,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2023\\\/12\\\/01\\\/marie-est-la\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marie est l\u00e0&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marie est l\u00e0... - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/","og_locale":"fr_FR","og_type":"article","og_title":"Marie est l\u00e0... - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle !","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2023-12-01T16:57:49+00:00","article_modified_time":"2026-01-06T16:05:57+00:00","og_image":[{"width":1298,"height":2560,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/12\/20231127_170021-scaled.jpg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"Marie est l\u00e0&#8230;","datePublished":"2023-12-01T16:57:49+00:00","dateModified":"2026-01-06T16:05:57+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/"},"wordCount":614,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/12\/20231127_170021-scaled.jpg","articleSection":["Apparitions du 19\u00e8me si\u00e8cle","Articles de Marie-Micka\u00ebl","Lourdes","R\u00e9v\u00e9lations pour la fin des temps"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/","name":"Marie est l\u00e0... - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/12\/20231127_170021-scaled.jpg","datePublished":"2023-12-01T16:57:49+00:00","dateModified":"2026-01-06T16:05:57+00:00","description":"Prier son chapelet permet \u00e0 Marie d\u2019entrer dans l\u2019intimit\u00e9 de notre c\u0153ur o\u00f9 elle enveloppe de sa tendresse maternelle notre pri\u00e8re, si pauvre soit-elle !","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/12\/20231127_170021-scaled.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/12\/20231127_170021-scaled.jpg","width":1298,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2023\/12\/01\/marie-est-la\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"Marie est l\u00e0&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=737"}],"version-history":[{"count":1,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/737\/revisions"}],"predecessor-version":[{"id":739,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/737\/revisions\/739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/738"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}