{"id":860,"date":"2024-01-26T16:48:35","date_gmt":"2024-01-26T16:48:35","guid":{"rendered":"https:\/\/refugesdemarie.fr\/?p=860"},"modified":"2026-01-06T16:05:35","modified_gmt":"2026-01-06T16:05:35","slug":"schisme-dites-vous-par-mark-mallett","status":"publish","type":"post","link":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/","title":{"rendered":"Schisme, dites-vous ? Par Mark Mallett"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/860?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/refugesdemarie.fr\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><\/a><\/div><p><a href=\"https:\/\/www.markmallett.com\/blog\/schism-you-say\/\">Par Mark Mallett, 19 janvier 2024<\/a><\/p>\n<p><strong data-moz-translations-id=\"0\">Quelqu&rsquo;un<\/strong> m&rsquo;a demand\u00e9 l&rsquo;autre jour: \u00abVous ne quittez pas le Saint-P\u00e8re ou le vrai magist\u00e8re, n&rsquo;est-ce pas?\u00bb J&rsquo;ai \u00e9t\u00e9 surpris par la question. \u00ab Non, qu&rsquo;est-ce qui t&rsquo;a donn\u00e9 cette impression ? \u00bb Il a dit qu&rsquo;il n&rsquo;en \u00e9tait pas s\u00fbr. Je l&rsquo;ai donc rassur\u00e9 que le schisme n&rsquo;est <em data-moz-translations-id=\"1\">pas<\/em> sur la table. Explication.<\/p>\n<h5>La parole de Dieu<\/h5>\n<p>Sa question arrive \u00e0 un moment o\u00f9 un feu a br\u00fble dans mon \u00e2me pour la <em data-moz-translations-id=\"0\">Parole de Dieu<\/em>. J&rsquo;en ai parl\u00e9 \u00e0 mon directeur spirituel, et m\u00eame lui connaissait cette faim int\u00e9rieure. Peut-\u00eatre que vous \u00eates aussi&#8230; C&rsquo;est presque comme si les controverses dans l&rsquo;\u00c9glise, la politique, la mesquinerie, les jeux de mots, l&rsquo;ambiguit\u00e9, l&rsquo;approbation des agendas mondiaux, etc.<img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-50392\" src=\"https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/Holy-Bible.jpg\" sizes=\"(max-width: 317px) 100vw, 317px\" srcset=\"https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/Holy-Bible.jpg 1000w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/Holy-Bible-200x300.jpg 200w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/Holy-Bible-683x1024.jpg 683w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/Holy-Bible-768x1152.jpg 768w\" alt=\"\" width=\"317\" height=\"476\" data-moz-translations-id=\"2\" \/>, me <em data-moz-translations-id=\"1\">ram\u00e8nent<\/em> dans la Parole de Dieu brute et non dilu\u00e9e. Je veux la d\u00e9vorer. <span class=\"footnote_referrer\" data-moz-translations-id=\"4\"><a tabindex=\"0\" role=\"button\" data-moz-translations-id=\"5\"><sup id=\"footnote_plugin_tooltip_50389_2_1\" class=\"footnote_plugin_tooltip_text\" data-moz-translations-id=\"6\">Et<\/sup><\/a> <\/span> Les \u00c9critures ne sont jamais \u00e9puis\u00e9es parce qu&rsquo;elles enseignent toujours, toujours nourrissantes, toujours \u00e9clairantes.<\/p>\n<p><span data-moz-translations-id=\"0\"><strong data-moz-translations-id=\"1\">En effet, la parole de Dieu est vivante et efficace, plus vive que n&rsquo;importe quelle \u00e9p\u00e9e \u00e0 deux tranchantss, p\u00e9n\u00e9trant m\u00eame entre l&rsquo;\u00e2me et l&rsquo;esprit, les articulations et la moelle, et capable de discerner les r\u00e9flexions et les pens\u00e9es du c\u0153ur.<\/strong> (Hb 4,12)<\/span><\/p>\n<p>Et pourtant, nous savons en tant que catholiques que l&rsquo;interpr\u00e9tation subjective de l&rsquo;\u00c9criture a des limites. Que le sens ultime des paroles du Christ a \u00e9t\u00e9 compris par les ap\u00f4tres et confi\u00e9s \u00e0 eux, et que leur enseignement nous a \u00e9t\u00e9 transmis \u00e0 travers les si\u00e8cles de succession apostolique.<span class=\"footnote_referrer\" data-moz-translations-id=\"0\"><a tabindex=\"0\" role=\"button\" data-moz-translations-id=\"1\"><sup id=\"footnote_plugin_tooltip_50389_2_2\" class=\"footnote_plugin_tooltip_text\" data-moz-translations-id=\"2\">[2]<\/sup><\/a><\/span> Ainsi, avec ceux que le Christ a command\u00e9s pour nous enseigner,<span class=\"footnote_referrer\" data-moz-translations-id=\"7\"><a tabindex=\"0\" role=\"button\" data-moz-translations-id=\"8\"><sup id=\"footnote_plugin_tooltip_50389_2_3\" class=\"footnote_plugin_tooltip_text\" data-moz-translations-id=\"9\">[3]<\/sup><\/a><\/span> nous nous tournons vers cette Tradition Sacr\u00e9e immuable et infaillible. Dans le cas contraire, il y aurait un chaos doctrinal.<\/p>\n<p>En m\u00eame temps, le pape et les \u00e9v\u00eaques en communion avec lui ne sont que des serviteurs de la Parole de Dieu. En tant que tels, nous sommes tous des disciples de cette Parole, des disciples de J\u00e9sus (voir <em data-moz-translations-id=\"0\"><a href=\"https:\/\/www.markmallett.com\/blog\/i-am-a-disciple-of-jesus-christ\/\" data-moz-translations-id=\"1\">je suis un Disciple de J\u00e9sus-Christ<\/a><\/em>). D&rsquo;o\u00f9&#8230;<\/p>\n<blockquote><p><span data-moz-translations-id=\"0\"><strong data-moz-translations-id=\"2\">&#8230; l&rsquo;\u00c9glise catholique n&rsquo;est pas l&rsquo;\u00c9glise du pape et les catholiques ne sont donc pas des papistes mais des chr\u00e9tiens. Le Christ est le chef de l&rsquo;\u00c9glise et de Lui toute la gr\u00e2ce divine et la v\u00e9rit\u00e9 passe aux membres de Son corps, qui est l&rsquo;\u00c9glise&#8230; les catholiques ne sont pas les sujets des sup\u00e9rieurs eccl\u00e9siastiques, auxquels ils doivent l&rsquo;ob\u00e9issance aveugle comme dans un syst\u00e8me politique totalitaire. En tant que personnes dans leur conscience et leur pri\u00e8re, elles vont directement \u00e0 Dieu en Christ et dans le Saint-Esprit. L&rsquo;acte de foi est dirig\u00e9 directement vers Dieu, tandis que le magist\u00e8re des \u00e9v\u00eaques n&rsquo;a que la t\u00e2che de pr\u00e9server fid\u00e8lement et compl\u00e8tement le contenu de la R\u00e9v\u00e9lation (donn\u00e9e dans l&rsquo;\u00c9criture sainte et la Tradition apostolique) et de le pr\u00e9senter \u00e0 l&rsquo;\u00c9glise comme r\u00e9v\u00e9l\u00e9 par Dieu.<\/strong> Cardinal Gerhard Muller, ancien pr\u00e9fet de la Congr\u00e9gation pour la doctrine de la foi, 18 janvier 2024, <\/span><\/p><\/blockquote>\n<p>Cette d\u00e9finition de base est un puits de lumi\u00e8re parfaitement actuelle dans le brouillard de confusion qui a divis\u00e9 les catholiques ces derni\u00e8res semaines. Les r\u00e9cents proc\u00e8s sont dus en grande partie \u00e0 une compr\u00e9hension exag\u00e9r\u00e9e de l&rsquo;infaillibilit\u00e9 papale et m\u00eame des attentes fausses de l&rsquo;homme qui occupe la fonction. Comme le note le cardinal dans la m\u00eame interview, \u00ab en termes de profondeur th\u00e9ologique et de pr\u00e9cision de l&rsquo;expression, le pape Beno\u00eet XVI \u00e9tait une exception plut\u00f4t que la norme dans l&rsquo;histoire mouvement\u00e9e des papes \u00bb. En effet, nous avons appr\u00e9ci\u00e9 l&rsquo;enseignement immacul\u00e9, m\u00eame dans le commentaire non-magistral de nos papes au cours du si\u00e8cle dernier. M\u00eame moi, j&rsquo;an \u00e9tais arriv\u00e9 au point de prendre pour acquis la facilit\u00e9 avec laquelle je pouvais les citer&#8230;<\/p>\n<h5>R\u00e9cup\u00e9ration de la perspective<\/h5>\n<p>Mais le pontife argentin est une autre histoire et un rappel que <em data-moz-translations-id=\"0\">l&rsquo;infaillibilit\u00e9<\/em> d&rsquo;un pape se limite aux rares occasions qu&rsquo;il \u00ab confirme ses fr\u00e8res dans la foi et proclame par un acte d\u00e9finitif une doctrine relative \u00e0 la foi ou \u00e0 <span class=\"footnote_referrer\" data-moz-translations-id=\"1\"><a tabindex=\"0\" role=\"button\" data-moz-translations-id=\"2\"><sup id=\"footnote_plugin_tooltip_50389_2_5\" class=\"footnote_plugin_tooltip_text\" data-moz-translations-id=\"3\">[5]<\/sup><\/a><\/span> morale \u00bb. Par cons\u00e9quent, la correction fraternelle n&rsquo;est pas au-del\u00e0 d&rsquo;un pape &#8211; \u00ab la plus connue est la question de l&rsquo;h\u00e9r\u00e9sie et de l&rsquo;excommunication du pape Honorius Ier \u00bb, note le cardinal M\u00fcller.<\/p>\n<div id=\"attachment_50393\" class=\"wp-caption alignright\">\n<p><img decoding=\"async\" class=\"wp-image-50393 \" src=\"https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/BarquePetros.jpg\" sizes=\"(max-width: 351px) 100vw, 351px\" srcset=\"https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/BarquePetros.jpg 1288w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/BarquePetros-300x223.jpg 300w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/BarquePetros-1024x760.jpg 1024w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2024\/01\/BarquePetros-768x570.jpg 768w\" alt=\"\" width=\"351\" height=\"261\" aria-describedby=\"caption-attachment-50393\" \/><\/p>\n<p id=\"caption-attachment-50393\" class=\"wp-caption-text\">Barque de Peter\/Photo par James Day<\/p>\n<\/div>\n<p>Par cons\u00e9quent, je crois que le Saint-Esprit utilise cette crise actuelle pour purger l&rsquo;\u00c9glise de <em data-moz-translations-id=\"0\">la papol\u00e2trie<\/em> &#8211; la notion errante que nos papes sont \u00ab un souverain absolu, dont les pens\u00e9es et les d\u00e9sirs sont la loi \u00bb.<span class=\"footnote_referrer\" data-moz-translations-id=\"1\"><a tabindex=\"0\" role=\"button\" data-moz-translations-id=\"2\"><sup id=\"footnote_plugin_tooltip_50389_2_7\" class=\"footnote_plugin_tooltip_text\" data-moz-translations-id=\"3\">[7]<\/sup><\/a><\/span> Tout en donnant l&rsquo;apparence de consolider l&rsquo;unit\u00e9, cette fausse croyance provoque en fait une division impie :<\/p>\n<p><span data-moz-translations-id=\"0\"><strong data-moz-translations-id=\"1\">Chaque fois que quelqu&rsquo;un dit, \u00ab J&rsquo;appartiens \u00e0 Paul \u00bb, et un autre, \u00ab J&rsquo;appartiens \u00e0 Apollos \u00bb, n&rsquo;\u00eates-vous pas seulement humain ?&#8230; car personne ne peut jeter un fondement autre que celui qui est l\u00e0, \u00e0 savoir J\u00e9sus-Christ.<\/strong> (1 Corinthiens 3:4, 11)<\/span><\/p>\n<p>Dans le m\u00eame temps, la Tradition elle-m\u00eame affirme la primaut\u00e9 de Pierre &#8211; et l&rsquo;impossibilit\u00e9 du schisme comme voie pour le troupeau :<\/p>\n<blockquote><p>&nbsp;<\/p>\n<p><span data-moz-translations-id=\"0\"><strong data-moz-translations-id=\"1\">Ils marchent donc sur le chemin d&rsquo;une erreur dangereuse qui croient qu&rsquo;ils peuvent accepter le Christ comme le chef de l&rsquo;\u00c9glise, tout en n&rsquo;adh\u00e9rant pas loyalement \u00e0 Son vicaire sur terre. Ils ont enlev\u00e9 la t\u00eate visible, bris\u00e9 les liens visibles de l&rsquo;unit\u00e9 et laiss\u00e9 le Corps mystique du R\u00e9dempteur si obscurci et si mutil\u00e9, que ceux qui cherchent le havre du salut \u00e9ternel ne peuvent ni le voir ni le trouver.<\/strong> Pape PIUS XII, <em data-moz-translations-id=\"2\">Mystici Corporis Christi<\/em> (Sur le corps mystique du Christ), 29 juin 1943; n. 41; <a href=\"http:\/\/w2.vatican.va\/content\/pius-xii\/en\/encyclicals\/documents\/hf_p-xii_enc_29061943_mystici-corporis-christi.html\" data-moz-translations-id=\"3\">vatican.va<\/a><\/span><\/p><\/blockquote>\n<p>Cette loyaut\u00e9 envers le pape n&rsquo;est cependant pas absolue. Elle est d\u00fbe lorsqu&rsquo;il exerce son \u00ab magist\u00e8re authentique \u00bb- exprimant des enseignements ou des d\u00e9clarations <em data-moz-translations-id=\"7\">\u00ab qui doivent toutefois \u00eatre explicitement ou implicitement contenues dans<\/em> <span class=\"footnote_referrer\" data-moz-translations-id=\"8\"><a tabindex=\"0\" role=\"button\" data-moz-translations-id=\"9\"><sup id=\"footnote_plugin_tooltip_50389_2_9\" class=\"footnote_plugin_tooltip_text\" data-moz-translations-id=\"10\">[9]<\/sup><\/a><\/span> la <em data-moz-translations-id=\"7\">r\u00e9v\u00e9lation \u00bb,<\/em> ajoute le cardinal M\u00fcller. C\u2019est ce qui rend l\u2019enseignement du successeur de Pierre \u00ab authentique \u00bb et essentiellement \u00ab catholique \u00bb. Par cons\u00e9quent, la r\u00e9cente correction fraternelle des \u00e9v\u00eaques n&rsquo;est pas une d\u00e9loyaut\u00e9 ou un rejet du pape, mais un soutien de ses fonctions.<\/p>\n<blockquote><p><span data-moz-translations-id=\"0\"><strong data-moz-translations-id=\"1\">Il ne s\u2019agit pas d\u2019\u00eatre \u00abpro-\u00bb pape Fran\u00e7ois ou \u00abcontra-\u00bb pape Fran\u00e7ois. Il s&rsquo;agit de d\u00e9fendre la foi catholique, et cela signifie d\u00e9fendre le Bureau de Pierre auquel le pape a succ\u00e9d\u00e9.<\/strong> Cardinal Raymond Burke, <a href=\"http:\/\/www.catholicworldreport.com\/2018\/01\/22\/cardinal-burke-it-is-a-source-of-anguish-to-hear-suggestions-that-i-would-lead-a-schism\/\" data-moz-translations-id=\"2\"><em data-moz-translations-id=\"3\">The Catholic World Report<\/em><\/a>, 22 janvier 2018<\/span><\/p><\/blockquote>\n<p>Vous n&rsquo;avez donc pas besoin de choisir les c\u00f4t\u00e9s &#8211; choisissez la Tradition Sacr\u00e9e puisque, en fin de compte, <em data-moz-translations-id=\"0\"><a href=\"https:\/\/www.markmallett.com\/blog\/the-papacy-is-not-one-pope\/\" data-moz-translations-id=\"1\">La papaut\u00e9 n&rsquo;est pas un pape<\/a><\/em>. Quelle grande trag\u00e9die que le monde regarde les catholiques causant le scandale, soit en tombant dans le schisme, soit en promouvant un culte de la personnalit\u00e9 autour du Pape, plut\u00f4t qu&rsquo;autour de J\u00e9sus.<\/p>\n<h5>Le temps du bain<\/h5>\n<p>Que comprendre \u00e0 travers ces \u00e9v\u00e8nements aujourd&rsquo;hui ? Je pense que c&rsquo;est l&rsquo;Esprit qui appelle l&rsquo;\u00c9glise, de haut en bas, \u00e0 tomber sur nos genoux et \u00e0 nous immerger \u00e0 nouveau dans la Parole de Dieu qui nous a \u00e9t\u00e9 donn\u00e9e dans les <img decoding=\"async\" class=\"alignleft wp-image-35992\" src=\"https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2019\/02\/st.-johnleaning4.jpg\" sizes=\"(max-width: 252px) 100vw, 252px\" srcset=\"https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2019\/02\/st.-johnleaning4.jpg 736w, https:\/\/www.markmallett.com\/blog\/wp-content\/uploads\/2019\/02\/st.-johnleaning4-295x300.jpg 295w\" alt=\"\" width=\"252\" height=\"256\" data-moz-translations-id=\"0\" \/>Saintes \u00c9critures. Comme je l&rsquo;ai \u00e9crit en <a href=\"https:\/\/www.markmallett.com\/blog\/novum\/\" data-moz-translations-id=\"1\"><em data-moz-translations-id=\"2\">Novum<\/em><\/a>, Notre Seigneur J\u00e9sus se pr\u00e9pare une Epouse sans t\u00e2che ni ride. Dans ce m\u00eame passage dans \u00c9ph\u00e9siens, Saint Paul nous dit <em data-moz-translations-id=\"3\">comment<\/em> :<\/p>\n<blockquote><p><span data-moz-translations-id=\"0\"><strong data-moz-translations-id=\"1\">Le Christ a aim\u00e9 l&rsquo;\u00e9glise et s&rsquo;est livr\u00e9 pour elle pour la sanctifier, <em data-moz-translations-id=\"2\">la purifiant par le bain d&rsquo;eau avec la Parole<\/em>&#8230;<\/strong> (Ep 5, 25-26)<\/span><\/p><\/blockquote>\n<p>Oui, c&rsquo;est le \u00ab mot de maintenant \u00bb pour aujourd&rsquo;hui : prenons nos bibles, chers fr\u00e8res et s\u0153urs, et laissons J\u00e9sus nous baigner dans Sa Parole &#8211; la Bible d&rsquo;une main, le Cat\u00e9chisme de l&rsquo;autre.<\/p>\n<p>Quant \u00e0 ceux qui flirtent avec le schisme, souvenez-vous&#8230; le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb. Et ce n&rsquo;est pas un bain sanctifiant.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Mark Mallett, 19 janvier 2024 Quelqu&rsquo;un m&rsquo;a demand\u00e9 l&rsquo;autre jour: \u00abVous ne quittez pas le Saint-P\u00e8re ou le vrai magist\u00e8re, n&rsquo;est-ce pas?\u00bb J&rsquo;ai \u00e9t\u00e9 surpris par la question. \u00ab Non, qu&rsquo;est-ce qui t&rsquo;a donn\u00e9 cette impression ? \u00bb Il a dit qu&rsquo;il n&rsquo;en \u00e9tait pas s\u00fbr. Je l&rsquo;ai donc rassur\u00e9 que le schisme n&rsquo;est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":861,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[44,4],"tags":[],"class_list":["post-860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enseignements-foi-parole","category-signes-des-temps","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schisme, dites-vous ? Par Mark Mallett - Communion des refuges du Coeur Immacul\u00e9 de Marie<\/title>\n<meta name=\"description\" content=\"A ceux qui flirtent avec le schisme, souvenez-vous... le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schisme, dites-vous ? Par Mark Mallett - Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"og:description\" content=\"A ceux qui flirtent avec le schisme, souvenez-vous... le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/\" \/>\n<meta property=\"og:site_name\" content=\"Communion des refuges du Coeur Immacul\u00e9 de Marie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100089561384328\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T16:48:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-06T16:05:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/01\/SchismBG-768x626-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"refugesdemarie@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"refugesdemarie@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/\"},\"author\":{\"name\":\"refugesdemarie@gmail.com\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\"},\"headline\":\"Schisme, dites-vous ? Par Mark Mallett\",\"datePublished\":\"2024-01-26T16:48:35+00:00\",\"dateModified\":\"2026-01-06T16:05:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/\"},\"wordCount\":1397,\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SchismBG-768x626-1.jpg\",\"articleSection\":[\"Enseignements (Foi, Parole...)\",\"Signes des temps\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/\",\"name\":\"Schisme, dites-vous ? Par Mark Mallett - Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SchismBG-768x626-1.jpg\",\"datePublished\":\"2024-01-26T16:48:35+00:00\",\"dateModified\":\"2026-01-06T16:05:35+00:00\",\"description\":\"A ceux qui flirtent avec le schisme, souvenez-vous... le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SchismBG-768x626-1.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SchismBG-768x626-1.jpg\",\"width\":768,\"height\":626},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/2024\\\/01\\\/26\\\/schisme-dites-vous-par-mark-mallett\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/refugesdemarie.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schisme, dites-vous ? Par Mark Mallett\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#website\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refugesdemarie.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#organization\",\"name\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"contentUrl\":\"https:\\\/\\\/refugesdemarie.fr\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-Logo-Communion-des-Refuges-6.jpg\",\"width\":1199,\"height\":377,\"caption\":\"Communion des refuges du Coeur Immacul\u00e9 de Marie\"},\"image\":{\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refugesdemarie.fr\\\/#\\\/schema\\\/person\\\/3bda0c49569f70f4dcfbe78b7e174b11\",\"name\":\"refugesdemarie@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g\",\"caption\":\"refugesdemarie@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/refugesdemarie.fr\",\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100089561384328\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXOznkQcnNvuMDGDg11ZPfg\"],\"url\":\"https:\\\/\\\/refugesdemarie.fr\\\/index.php\\\/author\\\/com-coeur-immaculegmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schisme, dites-vous ? Par Mark Mallett - Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"A ceux qui flirtent avec le schisme, souvenez-vous... le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/","og_locale":"fr_FR","og_type":"article","og_title":"Schisme, dites-vous ? Par Mark Mallett - Communion des refuges du Coeur Immacul\u00e9 de Marie","og_description":"A ceux qui flirtent avec le schisme, souvenez-vous... le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb.","og_url":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/","og_site_name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_author":"https:\/\/www.facebook.com\/profile.php?id=100089561384328","article_published_time":"2024-01-26T16:48:35+00:00","article_modified_time":"2026-01-06T16:05:35+00:00","og_image":[{"width":768,"height":626,"url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/01\/SchismBG-768x626-1.jpg","type":"image\/jpeg"}],"author":"refugesdemarie@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"refugesdemarie@gmail.com","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#article","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/"},"author":{"name":"refugesdemarie@gmail.com","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11"},"headline":"Schisme, dites-vous ? Par Mark Mallett","datePublished":"2024-01-26T16:48:35+00:00","dateModified":"2026-01-06T16:05:35+00:00","mainEntityOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/"},"wordCount":1397,"publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/01\/SchismBG-768x626-1.jpg","articleSection":["Enseignements (Foi, Parole...)","Signes des temps"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/","url":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/","name":"Schisme, dites-vous ? Par Mark Mallett - Communion des refuges du Coeur Immacul\u00e9 de Marie","isPartOf":{"@id":"https:\/\/refugesdemarie.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#primaryimage"},"image":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#primaryimage"},"thumbnailUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/01\/SchismBG-768x626-1.jpg","datePublished":"2024-01-26T16:48:35+00:00","dateModified":"2026-01-06T16:05:35+00:00","description":"A ceux qui flirtent avec le schisme, souvenez-vous... le seul son que vous entendrez si vous sautez de la Barque de Pierre est \u00ab splash \u00bb.","breadcrumb":{"@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#primaryimage","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/01\/SchismBG-768x626-1.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2024\/01\/SchismBG-768x626-1.jpg","width":768,"height":626},{"@type":"BreadcrumbList","@id":"https:\/\/refugesdemarie.fr\/index.php\/2024\/01\/26\/schisme-dites-vous-par-mark-mallett\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/refugesdemarie.fr\/"},{"@type":"ListItem","position":2,"name":"Schisme, dites-vous ? Par Mark Mallett"}]},{"@type":"WebSite","@id":"https:\/\/refugesdemarie.fr\/#website","url":"https:\/\/refugesdemarie.fr\/","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","description":"","publisher":{"@id":"https:\/\/refugesdemarie.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refugesdemarie.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/refugesdemarie.fr\/#organization","name":"Communion des refuges du Coeur Immacul\u00e9 de Marie","url":"https:\/\/refugesdemarie.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/","url":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","contentUrl":"https:\/\/refugesdemarie.fr\/wp-content\/uploads\/2023\/01\/cropped-Logo-Communion-des-Refuges-6.jpg","width":1199,"height":377,"caption":"Communion des refuges du Coeur Immacul\u00e9 de Marie"},"image":{"@id":"https:\/\/refugesdemarie.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100089561384328"]},{"@type":"Person","@id":"https:\/\/refugesdemarie.fr\/#\/schema\/person\/3bda0c49569f70f4dcfbe78b7e174b11","name":"refugesdemarie@gmail.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43491e46ee54b6706285b166679fe98aa620b1849d376153f6bc028852c019f7?s=96&d=mm&r=g","caption":"refugesdemarie@gmail.com"},"sameAs":["https:\/\/refugesdemarie.fr","https:\/\/www.facebook.com\/profile.php?id=100089561384328","https:\/\/www.youtube.com\/channel\/UCXOznkQcnNvuMDGDg11ZPfg"],"url":"https:\/\/refugesdemarie.fr\/index.php\/author\/com-coeur-immaculegmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=860"}],"version-history":[{"count":1,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/860\/revisions"}],"predecessor-version":[{"id":862,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/posts\/860\/revisions\/862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media\/861"}],"wp:attachment":[{"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refugesdemarie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}